{"id":108040,"date":"2021-04-27T19:39:39","date_gmt":"2021-04-28T00:39:39","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png"},"modified":"2021-04-27T19:39:39","modified_gmt":"2021-04-28T00:39:39","slug":"pj_2021-04-28_biden-100-days_b-01-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/journalism\/2021\/04\/28\/biden-administration-100-days-appendix-b-detailed-tables-comparing-news-coverage-of-the-first-100-days-vs-60-days-of-the-trump-administration-in-2017\/pj_2021-04-28_biden-100-days_b-01-png\/","title":{"rendered":"Top topics"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-108040","attachment","type-attachment","status-inherit","hentry"],"filename":"PJ_2021.04.28_biden-100-days_B-01.png","filesize":83181,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"243\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=243\" class=\"attachment-medium size-medium not-transparent\" alt=\"Top topics\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png 620w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=243,300 243w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=329,405 329w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=200,246 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=260,320 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=310,382 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=420,518 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=160,197 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?resize=320,394 320w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" data-has-transparency=\"false\" data-dominant-color=\"f4f4f4\" style=\"--dominant-color: #f4f4f4;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Top topics","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":764,"file":"2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png","filesize":83181,"sizes":{"thumbnail":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=150,150","width":150,"height":150,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=150&h=150&crop=1"},"medium":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=243,300","width":243,"height":300,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=243"},"A1":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=564,317","width":564,"height":317,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,634","width":620,"height":634,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,388","width":620,"height":388,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=388&crop=1"},"A2":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=268,151","width":268,"height":151,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=536,302","width":536,"height":302,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,388","width":620,"height":388,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=388&crop=1"},"A3":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=194,110","width":194,"height":110,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=388,220","width":388,"height":220,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=148,84","width":148,"height":84,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=296,168","width":296,"height":168,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=296&h=168&crop=1"},"A4":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=268,151","width":268,"height":151,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=536,302","width":536,"height":302,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,388","width":620,"height":388,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=388&crop=1"},"XL":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,405","width":620,"height":405,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=405&crop=1"},"social":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,628","width":620,"height":628,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=628&crop=1"},"chapter":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=329,405","width":329,"height":405,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=329"},"200-wide":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=200,246","width":200,"height":246,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=200"},"260-wide":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=260,320","width":260,"height":320,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=260"},"310-wide":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=310,382","width":310,"height":382,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=310"},"420-wide":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=420,518","width":420,"height":518,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=420"},"75-square":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=75,75","width":75,"height":75,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=140,140","width":140,"height":140,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=260,260","width":260,"height":260,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=160,197","width":160,"height":197,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=160"},"320-portrait":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=320,394","width":320,"height":394,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=320"},"200-by-133":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=200,133","width":200,"height":133,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=620,416","width":620,"height":416,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PJ_2021.04.28_biden-100-days_B-01.png?resize=540,304","width":540,"height":304,"filesize":83181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png?w=540&h=304&crop=1"},"full":{"file":"PJ_2021.04.28_biden-100-days_B-01.png","width":620,"height":764,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f4f4f4","has_transparency":false},"post":87670,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/04\/PJ_2021.04.28_biden-100-days_B-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Top topics","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/108040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=108040"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":87670,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/87670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}