{"id":109889,"date":"2019-02-25T13:06:44","date_gmt":"2019-02-25T18:06:44","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png"},"modified":"2019-02-25T13:06:44","modified_gmt":"2019-02-25T18:06:44","slug":"pj_2019-03-05_france-media_a-02-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/journalism\/2019\/04\/23\/france-media-attitudes-appendix-detailed-tables\/pj_2019-03-05_france-media_a-02-png\/","title":{"rendered":"News intake by education and income"},"author":377,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-109889","attachment","type-attachment","status-inherit","hentry"],"filename":"PJ_2019.03.05_France-media_A-02.png","filesize":69697,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"221\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"News intake by education and income\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png 848w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=300,221 300w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=768,567 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=549,405 549w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=200,148 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=260,192 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=310,229 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=420,310 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=640,472 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=740,546 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=160,118 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?resize=320,236 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"f5f5f5\" style=\"--dominant-color: #f5f5f5;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"News intake by education and income","media_type":"image","mime_type":"image\/png","media_details":{"width":848,"height":626,"file":"2019\/02\/PJ_2019.03.05_France-media_A-02.png","filesize":69697,"sizes":{"thumbnail":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=150,150","width":150,"height":150,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=150&h=150&crop=1"},"medium":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=300,221","width":300,"height":221,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=300"},"medium_large":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=768,567","width":768,"height":567,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=640"},"A1":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=564,317","width":564,"height":317,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=564&h=317&crop=1"},"A1-SMALL":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=690,388","width":690,"height":388,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=690&h=388&crop=1"},"A2":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=268,151","width":268,"height":151,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=536,302","width":536,"height":302,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=690,388","width":690,"height":388,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=690&h=388&crop=1"},"A3":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=194,110","width":194,"height":110,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=388,220","width":388,"height":220,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=148,84","width":148,"height":84,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=296,168","width":296,"height":168,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=296&h=168&crop=1"},"A4":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=268,151","width":268,"height":151,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=536,302","width":536,"height":302,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=690,388","width":690,"height":388,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=690&h=388&crop=1"},"XL":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=720,405","width":720,"height":405,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=720&h=405&crop=1"},"chapter":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=549,405","width":549,"height":405,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=549"},"200-wide":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=200,148","width":200,"height":148,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=200"},"260-wide":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=260,192","width":260,"height":192,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=260"},"310-wide":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=310,229","width":310,"height":229,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=310"},"420-wide":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=420,310","width":420,"height":310,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=420"},"640-wide":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=640,472","width":640,"height":472,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=640"},"740-wide":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=740,546","width":740,"height":546,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=740"},"75-square":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=75,75","width":75,"height":75,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=75&h=75&crop=1"},"140-square":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=140,140","width":140,"height":140,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=140&h=140&crop=1"},"260-square":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=260,260","width":260,"height":260,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=160,118","width":160,"height":118,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=160"},"320-portrait":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=320,236","width":320,"height":236,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=320"},"200-by-133":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=200,133","width":200,"height":133,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=740,416","width":740,"height":416,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PJ_2019.03.05_France-media_A-02.png?resize=540,304","width":540,"height":304,"filesize":69697,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png?w=540&h=304&crop=1"},"full":{"file":"PJ_2019.03.05_France-media_A-02.png","width":848,"height":626,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f5f5f5","has_transparency":false},"post":88052,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/02\/PJ_2019.03.05_France-media_A-02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"News intake by education and income","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/109889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=109889"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":88052,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/88052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}