{"id":165557,"date":"2024-05-03T15:37:02","date_gmt":"2024-05-03T19:37:02","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png"},"modified":"2024-05-03T17:20:53","modified_gmt":"2024-05-03T21:20:53","slug":"pg_06-22-22_poland_0_9","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2022\/06\/22\/spotlight-on-poland-negative-views-of-russia-surge-but-ratings-for-u-s-nato-eu-improve\/pg_06-22-22_poland_0_9\/","title":{"rendered":"Poles say country was strengthened by economic integration of Europe"},"author":648,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-165557","attachment","type-attachment","status-inherit","hentry"],"filename":"PG_06.22.22_Poland_0_9.png","filesize":89344,"_embeds":[],"table_of_contents":[{"id":27959,"title":"Spotlight on Poland: Negative Views of Russia Surge, but Ratings for U.S., NATO, EU Improve","slug":"spotlight-on-poland-negative-views-of-russia-surge-but-ratings-for-u-s-nato-eu-improve","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2022\/06\/22\/spotlight-on-poland-negative-views-of-russia-surge-but-ratings-for-u-s-nato-eu-improve\/","is_active":false},{"id":27948,"title":"Acknowledgments","slug":"poland-spring-2022-acknowledgments","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2022\/06\/22\/poland-spring-2022-acknowledgments\/","is_active":false},{"id":27975,"title":"Methodology","slug":"poland-spring-2022-methodology","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2022\/06\/22\/poland-spring-2022-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png'><img loading=\"lazy\" decoding=\"async\" width=\"142\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=142\" class=\"attachment-medium size-medium not-transparent\" alt=\"A pie chart showing that Poles say country was strengthened by economic integration of Europe\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png 410w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=142,300 142w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=192,405 192w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=200,422 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=260,549 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=310,655 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=152,320 152w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?resize=303,640 303w\" sizes=\"auto, (max-width: 142px) 100vw, 142px\" data-has-transparency=\"false\" data-dominant-color=\"d8dad0\" style=\"--dominant-color: #d8dad0;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A pie chart showing that Poles say country was strengthened by economic integration of Europe","media_type":"image","mime_type":"image\/png","media_details":{"width":410,"height":866,"file":"2024\/05\/PG_06.22.22_Poland_0_9.png","filesize":89344,"sizes":{"thumbnail":{"file":"PG_06.22.22_Poland_0_9.png?resize=150,150","width":150,"height":150,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=150&h=150&crop=1"},"medium":{"file":"PG_06.22.22_Poland_0_9.png?resize=142,300","width":142,"height":300,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=142"},"A1":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,317","width":410,"height":317,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=317&crop=1"},"A1-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,634","width":410,"height":634,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=634&crop=1"},"A1-SMALL":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,388","width":410,"height":388,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,776","width":410,"height":776,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=776&crop=1"},"A2":{"file":"PG_06.22.22_Poland_0_9.png?resize=268,151","width":268,"height":151,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,302","width":410,"height":302,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=302&crop=1"},"A2-SMALL":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,388","width":410,"height":388,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,776","width":410,"height":776,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=776&crop=1"},"A3":{"file":"PG_06.22.22_Poland_0_9.png?resize=194,110","width":194,"height":110,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=388,220","width":388,"height":220,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PG_06.22.22_Poland_0_9.png?resize=148,84","width":148,"height":84,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=296,168","width":296,"height":168,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=296&h=168&crop=1"},"A4":{"file":"PG_06.22.22_Poland_0_9.png?resize=268,151","width":268,"height":151,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,302","width":410,"height":302,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=302&crop=1"},"A4-SMALL":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,388","width":410,"height":388,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,776","width":410,"height":776,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=776&crop=1"},"XL":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,405","width":410,"height":405,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=405&crop=1"},"XL-HIDPI":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,810","width":410,"height":810,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=810&crop=1"},"social":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,628","width":410,"height":628,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=628&crop=1"},"chapter":{"file":"PG_06.22.22_Poland_0_9.png?resize=192,405","width":192,"height":405,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=192"},"200-wide":{"file":"PG_06.22.22_Poland_0_9.png?resize=200,422","width":200,"height":422,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=200"},"260-wide":{"file":"PG_06.22.22_Poland_0_9.png?resize=260,549","width":260,"height":549,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=260"},"310-wide":{"file":"PG_06.22.22_Poland_0_9.png?resize=310,655","width":310,"height":655,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=310"},"75-square":{"file":"PG_06.22.22_Poland_0_9.png?resize=75,75","width":75,"height":75,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=75&h=75&crop=1"},"140-square":{"file":"PG_06.22.22_Poland_0_9.png?resize=140,140","width":140,"height":140,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=140&h=140&crop=1"},"260-square":{"file":"PG_06.22.22_Poland_0_9.png?resize=260,260","width":260,"height":260,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PG_06.22.22_Poland_0_9.png?resize=152,320","width":152,"height":320,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=152"},"320-portrait":{"file":"PG_06.22.22_Poland_0_9.png?resize=303,640","width":303,"height":640,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=303"},"200-by-133":{"file":"PG_06.22.22_Poland_0_9.png?resize=200,133","width":200,"height":133,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,416","width":410,"height":416,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=416&crop=1"},"540-by-304":{"file":"PG_06.22.22_Poland_0_9.png?resize=410,304","width":410,"height":304,"filesize":89344,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png?w=410&h=304&crop=1"},"full":{"file":"PG_06.22.22_Poland_0_9.png","width":410,"height":866,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d8dad0","has_transparency":false},"post":27959,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/05\/PG_06.22.22_Poland_0_9.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Poles say country was strengthened by economic integration of Europe","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/165557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/648"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=165557"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":27959,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/27959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}