{"id":17305,"date":"2020-08-18T10:36:21","date_gmt":"2020-08-18T15:36:21","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png"},"modified":"2020-08-18T10:36:21","modified_gmt":"2020-08-18T15:36:21","slug":"ft_2020-08-18_multiracial_03-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2020\/08\/18\/key-findings-about-multiracial-identity-in-the-u-s-as-harris-becomes-vice-presidential-nominee\/ft_2020-08-18_multiracial_03-png\/","title":{"rendered":"In 2015, most adults with a multiracial background did not consider themselves \u2018multiracial\u2019"},"author":584,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-17305","attachment","type-attachment","status-inherit","hentry"],"filename":"ft_2020.08.18_multiracial_03.png","filesize":179733,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png'><img loading=\"lazy\" decoding=\"async\" width=\"152\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=152\" class=\"attachment-medium size-medium not-transparent\" alt=\"In 2015, most adults with a multiracial background did not consider themselves \u2018multiracial\u2019\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png 620w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=152,300 152w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=518,1024 518w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=205,405 205w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=200,395 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=260,514 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=310,613 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=420,831 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=160,316 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?resize=320,633 320w\" sizes=\"auto, (max-width: 152px) 100vw, 152px\" data-has-transparency=\"false\" data-dominant-color=\"dee3df\" style=\"--dominant-color: #dee3df;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"In 2015, most adults with a multiracial background did not consider themselves \u2018multiracial\u2019","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":1226,"file":"2020\/08\/ft_2020.08.18_multiracial_03.png","filesize":179733,"sizes":{"thumbnail":{"file":"ft_2020.08.18_multiracial_03.png?resize=150,150","width":150,"height":150,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=150&h=150&crop=1"},"medium":{"file":"ft_2020.08.18_multiracial_03.png?resize=152,300","width":152,"height":300,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=152"},"large":{"file":"ft_2020.08.18_multiracial_03.png?resize=518,1024","width":518,"height":1024,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=518"},"A1":{"file":"ft_2020.08.18_multiracial_03.png?resize=564,317","width":564,"height":317,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,634","width":620,"height":634,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,388","width":620,"height":388,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,776","width":620,"height":776,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=776&crop=1"},"A2":{"file":"ft_2020.08.18_multiracial_03.png?resize=268,151","width":268,"height":151,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=536,302","width":536,"height":302,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,388","width":620,"height":388,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,776","width":620,"height":776,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=776&crop=1"},"A3":{"file":"ft_2020.08.18_multiracial_03.png?resize=194,110","width":194,"height":110,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=388,220","width":388,"height":220,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"ft_2020.08.18_multiracial_03.png?resize=148,84","width":148,"height":84,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=296,168","width":296,"height":168,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=296&h=168&crop=1"},"A4":{"file":"ft_2020.08.18_multiracial_03.png?resize=268,151","width":268,"height":151,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=536,302","width":536,"height":302,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,388","width":620,"height":388,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,776","width":620,"height":776,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=776&crop=1"},"XL":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,405","width":620,"height":405,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,810","width":620,"height":810,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=810&crop=1"},"social":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,628","width":620,"height":628,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=628&crop=1"},"chapter":{"file":"ft_2020.08.18_multiracial_03.png?resize=205,405","width":205,"height":405,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=205"},"200-wide":{"file":"ft_2020.08.18_multiracial_03.png?resize=200,395","width":200,"height":395,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=200"},"260-wide":{"file":"ft_2020.08.18_multiracial_03.png?resize=260,514","width":260,"height":514,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=260"},"310-wide":{"file":"ft_2020.08.18_multiracial_03.png?resize=310,613","width":310,"height":613,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=310"},"420-wide":{"file":"ft_2020.08.18_multiracial_03.png?resize=420,831","width":420,"height":831,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=420"},"75-square":{"file":"ft_2020.08.18_multiracial_03.png?resize=75,75","width":75,"height":75,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=75&h=75&crop=1"},"140-square":{"file":"ft_2020.08.18_multiracial_03.png?resize=140,140","width":140,"height":140,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=140&h=140&crop=1"},"260-square":{"file":"ft_2020.08.18_multiracial_03.png?resize=260,260","width":260,"height":260,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"ft_2020.08.18_multiracial_03.png?resize=160,316","width":160,"height":316,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=160"},"320-portrait":{"file":"ft_2020.08.18_multiracial_03.png?resize=320,633","width":320,"height":633,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=320"},"200-by-133":{"file":"ft_2020.08.18_multiracial_03.png?resize=200,133","width":200,"height":133,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"ft_2020.08.18_multiracial_03.png?resize=620,416","width":620,"height":416,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=620&h=416&crop=1"},"540-by-304":{"file":"ft_2020.08.18_multiracial_03.png?resize=540,304","width":540,"height":304,"filesize":179733,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png?w=540&h=304&crop=1"},"full":{"file":"ft_2020.08.18_multiracial_03.png","width":620,"height":1226,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"dee3df","has_transparency":false},"post":9530,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/08\/ft_2020.08.18_multiracial_03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"In 2015, most adults with a multiracial background did not consider themselves \u2018multiracial\u2019","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/17305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/584"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=17305"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":9530,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/9530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}