{"id":179276,"date":"2024-06-21T14:31:05","date_gmt":"2024-06-21T18:31:05","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png"},"modified":"2024-06-21T14:56:25","modified_gmt":"2024-06-21T18:56:25","slug":"pp_2024-6-24_role-of-government_2-06","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2024\/06\/24\/americans-views-of-government-aid-to-poor-role-in-health-care-and-social-security\/pp_2024-6-24_role-of-government_2-06\/","title":{"rendered":"Overwhelming majority of Americans are against reducing Social Security benefits"},"author":581,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-179276","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_2024.6.24_role-of-government_2-06.png","filesize":169573,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png'><img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=226\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Overwhelming majority of Americans are against reducing Social Security benefits\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=226,300 226w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=768,1019 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=772,1024 772w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=305,405 305w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=200,265 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=260,345 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=310,411 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=420,557 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=640,849 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=740,981 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=160,212 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?resize=320,424 320w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" data-has-transparency=\"false\" data-dominant-color=\"e6e5de\" style=\"--dominant-color: #e6e5de;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Overwhelming majority of Americans are against reducing Social Security benefits","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1114,"file":"2024\/06\/PP_2024.6.24_role-of-government_2-06.png","filesize":169573,"sizes":{"thumbnail":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=150,150","width":150,"height":150,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=150&h=150&crop=1"},"medium":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=226,300","width":226,"height":300,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=226"},"medium_large":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=768,1019","width":768,"height":1019,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=640"},"large":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=772,1024","width":772,"height":1024,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=640"},"A1":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=564,317","width":564,"height":317,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=840,634","width":840,"height":634,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=690,388","width":690,"height":388,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=840,776","width":840,"height":776,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=840&h=776&crop=1"},"A2":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=268,151","width":268,"height":151,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=536,302","width":536,"height":302,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=690,388","width":690,"height":388,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=840,776","width":840,"height":776,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=840&h=776&crop=1"},"A3":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=194,110","width":194,"height":110,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=388,220","width":388,"height":220,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=148,84","width":148,"height":84,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=296,168","width":296,"height":168,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=296&h=168&crop=1"},"A4":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=268,151","width":268,"height":151,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=536,302","width":536,"height":302,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=690,388","width":690,"height":388,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=840,776","width":840,"height":776,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=840&h=776&crop=1"},"XL":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=720,405","width":720,"height":405,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=840,810","width":840,"height":810,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=840&h=810&crop=1"},"social":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=840,628","width":840,"height":628,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=840&h=628&crop=1"},"chapter":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=305,405","width":305,"height":405,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=305"},"200-wide":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=200,265","width":200,"height":265,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=200"},"260-wide":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=260,345","width":260,"height":345,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=260"},"310-wide":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=310,411","width":310,"height":411,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=310"},"420-wide":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=420,557","width":420,"height":557,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=420"},"640-wide":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=640,849","width":640,"height":849,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=640"},"740-wide":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=740,981","width":740,"height":981,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=740"},"75-square":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=75,75","width":75,"height":75,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=140,140","width":140,"height":140,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=260,260","width":260,"height":260,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=160,212","width":160,"height":212,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=160"},"320-portrait":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=320,424","width":320,"height":424,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=320"},"200-by-133":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=200,133","width":200,"height":133,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=740,416","width":740,"height":416,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PP_2024.6.24_role-of-government_2-06.png?resize=540,304","width":540,"height":304,"filesize":169573,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png?w=540&h=304&crop=1"},"full":{"file":"PP_2024.6.24_role-of-government_2-06.png","width":840,"height":1114,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e6e5de","has_transparency":false},"post":179241,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/06\/PP_2024.6.24_role-of-government_2-06.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Overwhelming majority of Americans are against reducing Social Security benefits","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/179276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=179276"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":179241,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/179241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}