{"id":19036,"date":"2020-03-02T10:03:23","date_gmt":"2020-03-02T15:03:23","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png"},"modified":"2020-03-02T10:03:23","modified_gmt":"2020-03-02T15:03:23","slug":"ft-20-02-24_trumpimmigrationenforcement_3-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2020\/03\/02\/how-border-apprehensions-ice-arrests-and-deportations-have-changed-under-trump\/ft-20-02-24_trumpimmigrationenforcement_3-png\/","title":{"rendered":"Removals of unauthorized immigrants rose 17% from 2017 to 2018, but remain below recent highs"},"author":459,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-19036","attachment","type-attachment","status-inherit","hentry"],"filename":"FT-20.02.24_TrumpImmigrationEnforcement_3.png","filesize":70224,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png'><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=259\" class=\"attachment-medium size-medium not-transparent\" alt=\"Removals of unauthorized immigrants rose 17% from 2017 to 2018, but remain below recent highs\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=259,300 259w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=768,891 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=349,405 349w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=200,232 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=260,301 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=310,359 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=420,487 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=640,742 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=740,858 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=160,186 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=320,371 320w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" data-has-transparency=\"false\" data-dominant-color=\"f6f5f4\" style=\"--dominant-color: #f6f5f4;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Removals of unauthorized immigrants rose 17% from 2017 to 2018, but remain below recent highs","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":974,"file":"2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png","filesize":70224,"sizes":{"thumbnail":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=150,150","width":150,"height":150,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=150&h=150&crop=1"},"medium":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=259,300","width":259,"height":300,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=259"},"medium_large":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=768,891","width":768,"height":891,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=640"},"A1":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=564,317","width":564,"height":317,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=840,634","width":840,"height":634,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=690,388","width":690,"height":388,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=840,776","width":840,"height":776,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=840&h=776&crop=1"},"A2":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=268,151","width":268,"height":151,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=536,302","width":536,"height":302,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=690,388","width":690,"height":388,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=840,776","width":840,"height":776,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=840&h=776&crop=1"},"A3":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=194,110","width":194,"height":110,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=388,220","width":388,"height":220,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=148,84","width":148,"height":84,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=296,168","width":296,"height":168,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=296&h=168&crop=1"},"A4":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=268,151","width":268,"height":151,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=536,302","width":536,"height":302,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=690,388","width":690,"height":388,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=840,776","width":840,"height":776,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=840&h=776&crop=1"},"XL":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=720,405","width":720,"height":405,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=840,810","width":840,"height":810,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=840&h=810&crop=1"},"social":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=840,628","width":840,"height":628,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=840&h=628&crop=1"},"chapter":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=349,405","width":349,"height":405,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=349"},"200-wide":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=200,232","width":200,"height":232,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=200"},"260-wide":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=260,301","width":260,"height":301,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=260"},"310-wide":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=310,359","width":310,"height":359,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=310"},"420-wide":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=420,487","width":420,"height":487,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=420"},"640-wide":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=640,742","width":640,"height":742,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=640"},"740-wide":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=740,858","width":740,"height":858,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=740"},"75-square":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=75,75","width":75,"height":75,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=75&h=75&crop=1"},"140-square":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=140,140","width":140,"height":140,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=140&h=140&crop=1"},"260-square":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=260,260","width":260,"height":260,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=260&h=260&crop=1"},"160-portrait":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=160,186","width":160,"height":186,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=160"},"320-portrait":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=320,371","width":320,"height":371,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=320"},"200-by-133":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=200,133","width":200,"height":133,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=200&h=133&crop=1"},"740-by-416":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=740,416","width":740,"height":416,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=740&h=416&crop=1"},"540-by-304":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png?resize=540,304","width":540,"height":304,"filesize":70224,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png?w=540&h=304&crop=1"},"full":{"file":"FT-20.02.24_TrumpImmigrationEnforcement_3.png","width":840,"height":974,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f6f5f4","has_transparency":false},"post":10158,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/03\/FT-20.02.24_TrumpImmigrationEnforcement_3.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Removals of unauthorized immigrants rose 17% from 2017 to 2018, but remain below recent highs","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/19036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/459"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=19036"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":10158,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/10158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}