{"id":26885,"date":"2014-04-07T11:08:19","date_gmt":"2014-04-07T16:08:19","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png"},"modified":"2014-04-07T11:08:19","modified_gmt":"2014-04-07T16:08:19","slug":"ft_14-04-07_stay-at-home-moms_choicenecessity310px-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2014\/04\/08\/7-key-findings-about-stay-at-home-moms\/ft_14-04-07_stay-at-home-moms_choicenecessity310px-png\/","title":{"rendered":"FT_14.04.07_Stay At Home Moms_choiceNecessity310px"},"author":130,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-26885","attachment","type-attachment","status-inherit","hentry"],"filename":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png","filesize":24827,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png'><img loading=\"lazy\" decoding=\"async\" width=\"242\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=242\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png 311w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=242,300 242w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=200,248 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=260,323 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=160,199 160w\" sizes=\"auto, (max-width: 242px) 100vw, 242px\" data-has-transparency=\"false\" data-dominant-color=\"e8ebe8\" style=\"--dominant-color: #e8ebe8;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":311,"height":386,"file":"2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png","filesize":24827,"sizes":{"thumbnail":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=150,150","width":150,"height":150,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=150&h=150&crop=1"},"medium":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=242,300","width":242,"height":300,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=242"},"A1":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=311,317","width":311,"height":317,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=311&h=317&crop=1"},"A2":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=268,151","width":268,"height":151,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=311,302","width":311,"height":302,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=311&h=302&crop=1"},"A3":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=194,110","width":194,"height":110,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=311,220","width":311,"height":220,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=311&h=220&crop=1"},"A3-SMALL":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=148,84","width":148,"height":84,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=296,168","width":296,"height":168,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=296&h=168&crop=1"},"A4":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=268,151","width":268,"height":151,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=311,302","width":311,"height":302,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=311&h=302&crop=1"},"200-wide":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=200,248","width":200,"height":248,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=200"},"260-wide":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=260,323","width":260,"height":323,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=260"},"75-square":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=75,75","width":75,"height":75,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=75&h=75&crop=1"},"140-square":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=140,140","width":140,"height":140,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=140&h=140&crop=1"},"260-square":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=260,260","width":260,"height":260,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=260&h=260&crop=1"},"160-portrait":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=160,199","width":160,"height":199,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=160"},"200-by-133":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=200,133","width":200,"height":133,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=200&h=133&crop=1"},"540-by-304":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?resize=311,304","width":311,"height":304,"filesize":24827,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png?w=311&h=304&crop=1"},"full":{"file":"FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png","width":311,"height":386,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e8ebe8","has_transparency":false},"post":14491,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2014\/04\/FT_14.04.07_Stay-At-Home-Moms_choiceNecessity310px.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"FT_14.04.07_Stay At Home Moms_choiceNecessity310px","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/26885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/130"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=26885"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":14491,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/14491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}