{"id":38216,"date":"2016-10-04T14:22:06","date_gmt":"2016-10-04T19:22:06","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png"},"modified":"2016-10-04T14:22:06","modified_gmt":"2016-10-04T19:22:06","slug":"10-4-2016-9-39-43-am-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2016\/10\/05\/chinese-public-sees-more-powerful-role-in-world-names-u-s-as-top-threat\/10-4-2016-9-39-43-am-png\/","title":{"rendered":"Corrupt officials are top Chinese concern"},"author":392,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-38216","attachment","type-attachment","status-inherit","hentry"],"filename":"10-4-2016-9-39-43-AM.png","filesize":10973,"_embeds":[],"table_of_contents":[{"id":29428,"title":"Chinese Public Sees More Powerful Role in World, Names U.S. as Top Threat","slug":"chinese-public-sees-more-powerful-role-in-world-names-u-s-as-top-threat","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2016\/10\/05\/chinese-public-sees-more-powerful-role-in-world-names-u-s-as-top-threat\/","is_active":false},{"id":29420,"title":"1. Chinese views on the economy and domestic challenges","slug":"1-chinese-views-on-the-economy-and-domestic-challenges","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2016\/10\/05\/1-chinese-views-on-the-economy-and-domestic-challenges\/","is_active":false},{"id":29414,"title":"2. China and the world","slug":"2-china-and-the-world","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2016\/10\/05\/2-china-and-the-world\/","is_active":false},{"id":29410,"title":"Acknowledgments","slug":"acknowledgments-10","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2016\/10\/05\/acknowledgments-10\/","is_active":false},{"id":29404,"title":"Methodology","slug":"methodology-32","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/global\/2016\/10\/05\/methodology-32\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=225\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png 422w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=225,300 225w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=304,405 304w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=200,266 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=260,346 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=310,413 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=420,559 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=160,213 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?resize=320,426 320w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" data-has-transparency=\"false\" data-dominant-color=\"e8e9dc\" style=\"--dominant-color: #e8e9dc;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":422,"height":562,"file":"2016\/10\/10-4-2016-9-39-43-AM.png","filesize":10973,"sizes":{"thumbnail":{"file":"10-4-2016-9-39-43-AM.png?resize=150,150","width":150,"height":150,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=150&h=150&crop=1"},"medium":{"file":"10-4-2016-9-39-43-AM.png?resize=225,300","width":225,"height":300,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=225"},"A1":{"file":"10-4-2016-9-39-43-AM.png?resize=422,317","width":422,"height":317,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=317&crop=1"},"A1-SMALL":{"file":"10-4-2016-9-39-43-AM.png?resize=422,388","width":422,"height":388,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=388&crop=1"},"A2":{"file":"10-4-2016-9-39-43-AM.png?resize=268,151","width":268,"height":151,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"10-4-2016-9-39-43-AM.png?resize=422,302","width":422,"height":302,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=302&crop=1"},"A2-SMALL":{"file":"10-4-2016-9-39-43-AM.png?resize=422,388","width":422,"height":388,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=388&crop=1"},"A3":{"file":"10-4-2016-9-39-43-AM.png?resize=194,110","width":194,"height":110,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"10-4-2016-9-39-43-AM.png?resize=388,220","width":388,"height":220,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"10-4-2016-9-39-43-AM.png?resize=148,84","width":148,"height":84,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"10-4-2016-9-39-43-AM.png?resize=296,168","width":296,"height":168,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=296&h=168&crop=1"},"A4":{"file":"10-4-2016-9-39-43-AM.png?resize=268,151","width":268,"height":151,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"10-4-2016-9-39-43-AM.png?resize=422,302","width":422,"height":302,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=302&crop=1"},"A4-SMALL":{"file":"10-4-2016-9-39-43-AM.png?resize=422,388","width":422,"height":388,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=388&crop=1"},"XL":{"file":"10-4-2016-9-39-43-AM.png?resize=422,405","width":422,"height":405,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=405&crop=1"},"chapter":{"file":"10-4-2016-9-39-43-AM.png?resize=304,405","width":304,"height":405,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=304"},"200-wide":{"file":"10-4-2016-9-39-43-AM.png?resize=200,266","width":200,"height":266,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=200"},"260-wide":{"file":"10-4-2016-9-39-43-AM.png?resize=260,346","width":260,"height":346,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=260"},"310-wide":{"file":"10-4-2016-9-39-43-AM.png?resize=310,413","width":310,"height":413,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=310"},"420-wide":{"file":"10-4-2016-9-39-43-AM.png?resize=420,559","width":420,"height":559,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=420"},"75-square":{"file":"10-4-2016-9-39-43-AM.png?resize=75,75","width":75,"height":75,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=75&h=75&crop=1"},"140-square":{"file":"10-4-2016-9-39-43-AM.png?resize=140,140","width":140,"height":140,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=140&h=140&crop=1"},"260-square":{"file":"10-4-2016-9-39-43-AM.png?resize=260,260","width":260,"height":260,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=260&h=260&crop=1"},"160-portrait":{"file":"10-4-2016-9-39-43-AM.png?resize=160,213","width":160,"height":213,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=160"},"320-portrait":{"file":"10-4-2016-9-39-43-AM.png?resize=320,426","width":320,"height":426,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=320"},"200-by-133":{"file":"10-4-2016-9-39-43-AM.png?resize=200,133","width":200,"height":133,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=200&h=133&crop=1"},"740-by-416":{"file":"10-4-2016-9-39-43-AM.png?resize=422,416","width":422,"height":416,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=416&crop=1"},"540-by-304":{"file":"10-4-2016-9-39-43-AM.png?resize=422,304","width":422,"height":304,"filesize":10973,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png?w=422&h=304&crop=1"},"full":{"file":"10-4-2016-9-39-43-AM.png","width":422,"height":562,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e8e9dc","has_transparency":false},"post":29428,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2016\/10\/10-4-2016-9-39-43-AM.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Corrupt officials are top Chinese concern","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/38216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/392"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=38216"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":29428,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/29428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}