{"id":49130,"date":"2019-01-29T17:02:30","date_gmt":"2019-01-29T22:02:30","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg"},"modified":"2019-01-29T17:02:30","modified_gmt":"2019-01-29T22:02:30","slug":"ft_18-12-31_2020-electorate_310px_2x1-jpg","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/social-trends\/2019\/01\/30\/an-early-look-at-the-2020-electorate-2\/ft_18-12-31_2020-electorate_310px_2x1-jpg\/","title":{"rendered":"FT_18.12.31_2020-Electorate_310px_2x"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-49130","attachment","type-attachment","status-inherit","hentry"],"filename":"FT_18.12.31_2020-Electorate_310px_2x1.jpg","filesize":51588,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp'><img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=190\" class=\"attachment-medium size-medium not-transparent\" alt=\"\" data-has-transparency=\"false\" data-dominant-color=\"e4e3e1\" style=\"--dominant-color: #e4e3e1;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":620,"height":979,"file":"2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp","filesize":51588,"sizes":{"thumbnail":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=150,150","width":150,"height":150,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=150&h=150&crop=1"},"medium":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=190,300","width":190,"height":300,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=190"},"A1":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=564,317","width":564,"height":317,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,634","width":620,"height":634,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=634&crop=1"},"A1-SMALL":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,388","width":620,"height":388,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,776","width":620,"height":776,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=776&crop=1"},"A2":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=268,151","width":268,"height":151,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=536,302","width":536,"height":302,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=536&h=302&crop=1"},"A2-SMALL":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,388","width":620,"height":388,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,776","width":620,"height":776,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=776&crop=1"},"A3":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=194,110","width":194,"height":110,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=388,220","width":388,"height":220,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=388&h=220&crop=1"},"A3-SMALL":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=148,84","width":148,"height":84,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=296,168","width":296,"height":168,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=296&h=168&crop=1"},"A4":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=268,151","width":268,"height":151,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=536,302","width":536,"height":302,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=536&h=302&crop=1"},"A4-SMALL":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,388","width":620,"height":388,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,776","width":620,"height":776,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=776&crop=1"},"XL":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,405","width":620,"height":405,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,810","width":620,"height":810,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=810&crop=1"},"social":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,628","width":620,"height":628,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=628&crop=1"},"chapter":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=256,405","width":256,"height":405,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=256"},"200-wide":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=200,316","width":200,"height":316,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=200"},"260-wide":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=260,411","width":260,"height":411,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=260"},"310-wide":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=310,490","width":310,"height":490,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=310"},"420-wide":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=420,663","width":420,"height":663,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=420"},"75-square":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=75,75","width":75,"height":75,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=75&h=75&crop=1"},"140-square":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=140,140","width":140,"height":140,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=140&h=140&crop=1"},"260-square":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=260,260","width":260,"height":260,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=260&h=260&crop=1"},"160-portrait":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=160,253","width":160,"height":253,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=160"},"320-portrait":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=320,505","width":320,"height":505,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=320"},"200-by-133":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=200,133","width":200,"height":133,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=200&h=133&crop=1"},"740-by-416":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=620,416","width":620,"height":416,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=620&h=416&crop=1"},"540-by-304":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp?resize=540,304","width":540,"height":304,"filesize":51588,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg?w=540&h=304&crop=1"},"full":{"file":"FT_18.12.31_2020-Electorate_310px_2x1.jpg","width":620,"height":979,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e4e3e1","has_transparency":false,"sources":{"image\/webp":{"file":"FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp","filesize":51588}},"original_image":"FT_18.12.31_2020-Electorate_310px_2x1.jpg"},"post":39416,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2019\/01\/FT_18.12.31_2020-Electorate_310px_2x1-jpg.webp","jetpack_videopress_guid":"","jetpack_videopress":{"title":"FT_18.12.31_2020-Electorate_310px_2x","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/49130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=49130"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":39416,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/39416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}