{"id":58044,"date":"2023-06-27T10:54:36","date_gmt":"2023-06-27T15:54:36","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png"},"modified":"2023-06-27T10:54:36","modified_gmt":"2023-06-27T15:54:36","slug":"pp_2023-06-28_gun-violence_2-02-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2023\/06\/28\/gun-violence-widely-viewed-as-a-major-and-growing-national-problem\/pp_2023-06-28_gun-violence_2-02-png\/","title":{"rendered":"Gun owners, non-owners differ over many gun policy proposals"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-58044","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_2023.06.28_gun-violence_2-02.png","filesize":221675,"_embeds":[],"table_of_contents":[{"id":46050,"title":"Gun Violence Widely Viewed as a Major \u2013 and Growing \u2013 National Problem","slug":"gun-violence-widely-viewed-as-a-major-and-growing-national-problem","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2023\/06\/28\/gun-violence-widely-viewed-as-a-major-and-growing-national-problem\/","is_active":false},{"id":46062,"title":"1. Views of U.S. gun laws, impact of gun ownership on safety","slug":"views-of-u-s-gun-laws-impact-of-gun-ownership-on-safety","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2023\/06\/28\/views-of-u-s-gun-laws-impact-of-gun-ownership-on-safety\/","is_active":false},{"id":46057,"title":"2. Americans\u2019 views of specific gun policy proposals","slug":"americans-views-of-specific-gun-policy-proposals","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2023\/06\/28\/americans-views-of-specific-gun-policy-proposals\/","is_active":false},{"id":46044,"title":"Acknowledgments","slug":"gun-violence-acknowledgments","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2023\/06\/28\/gun-violence-acknowledgments\/","is_active":false},{"id":46038,"title":"Methodology","slug":"gun-violence-methodology","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2023\/06\/28\/gun-violence-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png'><img loading=\"lazy\" decoding=\"async\" width=\"257\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=257\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows Gun owners, non-owners differ over many gun policy proposals\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=257,300 257w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=768,898 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=346,405 346w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=200,234 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=260,304 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=310,362 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=420,491 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=640,748 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=740,865 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=160,187 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?resize=320,374 320w\" sizes=\"auto, (max-width: 257px) 100vw, 257px\" data-has-transparency=\"false\" data-dominant-color=\"efefee\" style=\"--dominant-color: #efefee;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows Gun owners, non-owners differ over many gun policy proposals","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":982,"file":"2023\/06\/PP_2023.06.28_gun-violence_2-02.png","filesize":221675,"sizes":{"thumbnail":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=150,150","width":150,"height":150,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=150&h=150&crop=1"},"medium":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=257,300","width":257,"height":300,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=257"},"medium_large":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=768,898","width":768,"height":898,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=640"},"A1":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=564,317","width":564,"height":317,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=840,634","width":840,"height":634,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=690,388","width":690,"height":388,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=840,776","width":840,"height":776,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=840&h=776&crop=1"},"A2":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=268,151","width":268,"height":151,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=536,302","width":536,"height":302,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=690,388","width":690,"height":388,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=840,776","width":840,"height":776,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=840&h=776&crop=1"},"A3":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=194,110","width":194,"height":110,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=388,220","width":388,"height":220,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=148,84","width":148,"height":84,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=296,168","width":296,"height":168,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=296&h=168&crop=1"},"A4":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=268,151","width":268,"height":151,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=536,302","width":536,"height":302,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=690,388","width":690,"height":388,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=840,776","width":840,"height":776,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=840&h=776&crop=1"},"XL":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=720,405","width":720,"height":405,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=840,810","width":840,"height":810,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=840&h=810&crop=1"},"social":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=840,628","width":840,"height":628,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=840&h=628&crop=1"},"chapter":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=346,405","width":346,"height":405,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=346"},"200-wide":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=200,234","width":200,"height":234,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=200"},"260-wide":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=260,304","width":260,"height":304,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=260"},"310-wide":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=310,362","width":310,"height":362,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=310"},"420-wide":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=420,491","width":420,"height":491,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=420"},"640-wide":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=640,748","width":640,"height":748,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=640"},"740-wide":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=740,865","width":740,"height":865,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=740"},"75-square":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=75,75","width":75,"height":75,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=140,140","width":140,"height":140,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=260,260","width":260,"height":260,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=160,187","width":160,"height":187,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=160"},"320-portrait":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=320,374","width":320,"height":374,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=320"},"200-by-133":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=200,133","width":200,"height":133,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=740,416","width":740,"height":416,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PP_2023.06.28_gun-violence_2-02.png?resize=540,304","width":540,"height":304,"filesize":221675,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png?w=540&h=304&crop=1"},"full":{"file":"PP_2023.06.28_gun-violence_2-02.png","width":840,"height":982,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"efefee","has_transparency":false},"post":46050,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/06\/PP_2023.06.28_gun-violence_2-02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Gun owners, non-owners differ over many gun policy proposals","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/58044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=58044"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":46050,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/46050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}