{"id":58929,"date":"2021-09-23T12:48:19","date_gmt":"2021-09-23T17:48:19","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png"},"modified":"2021-09-23T12:48:19","modified_gmt":"2021-09-23T17:48:19","slug":"pp_2021-09-23_biden-approval_02-06-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2021\/09\/23\/national-economic-ratings-and-concerns\/pp_2021-09-23_biden-approval_02-06-png\/","title":{"rendered":"Adults with lower incomes more likely to be very concerned about evictions and foreclosures, job availability"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-58929","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_2021.09.23_biden-approval_02-06.png","filesize":85980,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"241\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows adults with lower incomes more likely to be very concerned about evictions and foreclosures, job availability\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=300,241 300w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=768,618 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=503,405 503w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=200,161 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=260,209 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=310,249 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=420,338 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=640,515 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=740,596 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=160,129 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?resize=320,258 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"f0f0ef\" style=\"--dominant-color: #f0f0ef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows adults with lower incomes more likely to be very concerned about evictions and foreclosures, job availability","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":676,"file":"2021\/09\/PP_2021.09.23_biden-approval_02-06.png","filesize":85980,"sizes":{"thumbnail":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=150,150","width":150,"height":150,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=150&h=150&crop=1"},"medium":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=300,241","width":300,"height":241,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=300"},"medium_large":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=768,618","width":768,"height":618,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=640"},"A1":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=564,317","width":564,"height":317,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=840,634","width":840,"height":634,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=690,388","width":690,"height":388,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=690&h=388&crop=1"},"A2":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=268,151","width":268,"height":151,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=536,302","width":536,"height":302,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=690,388","width":690,"height":388,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=690&h=388&crop=1"},"A3":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=194,110","width":194,"height":110,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=388,220","width":388,"height":220,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=148,84","width":148,"height":84,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=296,168","width":296,"height":168,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=296&h=168&crop=1"},"A4":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=268,151","width":268,"height":151,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=536,302","width":536,"height":302,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=690,388","width":690,"height":388,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=690&h=388&crop=1"},"XL":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=720,405","width":720,"height":405,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=720&h=405&crop=1"},"social":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=840,628","width":840,"height":628,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=840&h=628&crop=1"},"chapter":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=503,405","width":503,"height":405,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=503"},"200-wide":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=200,161","width":200,"height":161,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=200"},"260-wide":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=260,209","width":260,"height":209,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=260"},"310-wide":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=310,249","width":310,"height":249,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=310"},"420-wide":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=420,338","width":420,"height":338,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=420"},"640-wide":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=640,515","width":640,"height":515,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=640"},"740-wide":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=740,596","width":740,"height":596,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=740"},"75-square":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=75,75","width":75,"height":75,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=140,140","width":140,"height":140,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=260,260","width":260,"height":260,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=160,129","width":160,"height":129,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=160"},"320-portrait":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=320,258","width":320,"height":258,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=320"},"200-by-133":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=200,133","width":200,"height":133,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=740,416","width":740,"height":416,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PP_2021.09.23_biden-approval_02-06.png?resize=540,304","width":540,"height":304,"filesize":85980,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png?w=540&h=304&crop=1"},"full":{"file":"PP_2021.09.23_biden-approval_02-06.png","width":840,"height":676,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f0f0ef","has_transparency":false},"post":46963,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/09\/PP_2021.09.23_biden-approval_02-06.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Adults with lower incomes more likely to be very concerned about evictions and foreclosures, job availability","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/58929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=58929"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":46963,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/46963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}