{"id":59060,"date":"2021-03-18T11:21:50","date_gmt":"2021-03-18T16:21:50","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png"},"modified":"2021-03-18T11:21:50","modified_gmt":"2021-03-18T16:21:50","slug":"pp_2021-03-18_capitol-riots_m-01-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2021\/03\/18\/capitol-riot-views-methodology\/pp_2021-03-18_capitol-riots_m-01-png\/","title":{"rendered":"American Trends Panel recruitment surveys"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-59060","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_2021.03.18_capitol-riots_M-01.png","filesize":87181,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"232\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Table shows American Trends Panel recruitment surveys\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=300,232 300w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=768,594 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=523,405 523w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=200,155 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=260,201 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=310,240 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=420,325 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=640,495 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=740,573 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=160,124 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?resize=320,248 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"eeeeee\" style=\"--dominant-color: #eeeeee;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Table shows American Trends Panel recruitment surveys","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":650,"file":"2021\/03\/PP_2021.03.18_capitol-riots_M-01.png","filesize":87181,"sizes":{"thumbnail":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=150,150","width":150,"height":150,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=150&h=150&crop=1"},"medium":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=300,232","width":300,"height":232,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=300"},"medium_large":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=768,594","width":768,"height":594,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=640"},"A1":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=564,317","width":564,"height":317,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=840,634","width":840,"height":634,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=690,388","width":690,"height":388,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=690&h=388&crop=1"},"A2":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=268,151","width":268,"height":151,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=536,302","width":536,"height":302,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=690,388","width":690,"height":388,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=690&h=388&crop=1"},"A3":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=194,110","width":194,"height":110,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=388,220","width":388,"height":220,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=148,84","width":148,"height":84,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=296,168","width":296,"height":168,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=296&h=168&crop=1"},"A4":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=268,151","width":268,"height":151,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=536,302","width":536,"height":302,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=690,388","width":690,"height":388,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=690&h=388&crop=1"},"XL":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=720,405","width":720,"height":405,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=720&h=405&crop=1"},"social":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=840,628","width":840,"height":628,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=840&h=628&crop=1"},"chapter":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=523,405","width":523,"height":405,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=523"},"200-wide":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=200,155","width":200,"height":155,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=200"},"260-wide":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=260,201","width":260,"height":201,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=260"},"310-wide":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=310,240","width":310,"height":240,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=310"},"420-wide":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=420,325","width":420,"height":325,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=420"},"640-wide":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=640,495","width":640,"height":495,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=640"},"740-wide":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=740,573","width":740,"height":573,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=740"},"75-square":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=75,75","width":75,"height":75,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=140,140","width":140,"height":140,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=260,260","width":260,"height":260,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=160,124","width":160,"height":124,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=160"},"320-portrait":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=320,248","width":320,"height":248,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=320"},"200-by-133":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=200,133","width":200,"height":133,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=740,416","width":740,"height":416,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PP_2021.03.18_capitol-riots_M-01.png?resize=540,304","width":540,"height":304,"filesize":87181,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png?w=540&h=304&crop=1"},"full":{"file":"PP_2021.03.18_capitol-riots_M-01.png","width":840,"height":650,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eeeeee","has_transparency":false},"post":47166,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/03\/PP_2021.03.18_capitol-riots_M-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"American Trends Panel recruitment surveys","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/59060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=59060"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":47166,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/47166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}