{"id":59401,"date":"2021-01-14T19:06:08","date_gmt":"2021-01-15T00:06:08","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png"},"modified":"2021-01-14T19:06:08","modified_gmt":"2021-01-15T00:06:08","slug":"pp_2021-01-14_biden-trump-views_03-03-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/politics\/2021\/01\/15\/views-on-the-rioting-at-the-u-s-capitol\/pp_2021-01-14_biden-trump-views_03-03-png\/","title":{"rendered":"Ideological divide in GOP over Trump\u2019s future role in politics"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-59401","attachment","type-attachment","status-inherit","hentry"],"filename":"PP_2021.01.14_biden-trump-views_03-03.png","filesize":67550,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=226\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows ideological divide in GOP over Trump\u2019s future role in politics\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png 620w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=226,300 226w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=305,405 305w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=200,266 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=260,346 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=310,412 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=420,558 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=160,213 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?resize=320,425 320w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" data-has-transparency=\"false\" data-dominant-color=\"f3f0ea\" style=\"--dominant-color: #f3f0ea;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows ideological divide in GOP over Trump\u2019s future role in politics","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":824,"file":"2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png","filesize":67550,"sizes":{"thumbnail":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=150,150","width":150,"height":150,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=150&h=150&crop=1"},"medium":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=226,300","width":226,"height":300,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=226"},"A1":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=564,317","width":564,"height":317,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,634","width":620,"height":634,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,388","width":620,"height":388,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,776","width":620,"height":776,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=776&crop=1"},"A2":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=268,151","width":268,"height":151,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=536,302","width":536,"height":302,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,388","width":620,"height":388,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,776","width":620,"height":776,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=776&crop=1"},"A3":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=194,110","width":194,"height":110,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=388,220","width":388,"height":220,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=148,84","width":148,"height":84,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=296,168","width":296,"height":168,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=296&h=168&crop=1"},"A4":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=268,151","width":268,"height":151,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=536,302","width":536,"height":302,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,388","width":620,"height":388,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,776","width":620,"height":776,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=776&crop=1"},"XL":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,405","width":620,"height":405,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=405&crop=1"},"XL-HIDPI":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,810","width":620,"height":810,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=810&crop=1"},"social":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,628","width":620,"height":628,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=628&crop=1"},"chapter":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=305,405","width":305,"height":405,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=305"},"200-wide":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=200,266","width":200,"height":266,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=200"},"260-wide":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=260,346","width":260,"height":346,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=260"},"310-wide":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=310,412","width":310,"height":412,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=310"},"420-wide":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=420,558","width":420,"height":558,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=420"},"75-square":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=75,75","width":75,"height":75,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=140,140","width":140,"height":140,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=260,260","width":260,"height":260,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=160,213","width":160,"height":213,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=160"},"320-portrait":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=320,425","width":320,"height":425,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=320"},"200-by-133":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=200,133","width":200,"height":133,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=620,416","width":620,"height":416,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=620&h=416&crop=1"},"540-by-304":{"file":"PP_2021.01.14_biden-trump-views_03-03.png?resize=540,304","width":540,"height":304,"filesize":67550,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png?w=540&h=304&crop=1"},"full":{"file":"PP_2021.01.14_biden-trump-views_03-03.png","width":620,"height":824,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f3f0ea","has_transparency":false},"post":47199,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2021\/01\/PP_2021.01.14_biden-trump-views_03-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Ideological divide in GOP over Trump\u2019s future role in politics","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/59401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=59401"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":47199,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/47199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}