{"id":7395,"date":"2020-09-22T19:52:32","date_gmt":"2020-09-23T00:52:32","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png"},"modified":"2020-09-22T19:52:32","modified_gmt":"2020-09-23T00:52:32","slug":"ps_2020-09-29_factsheet-canada_0-03-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/science\/fact-sheet\/public-views-about-science-in-canada\/ps_2020-09-29_factsheet-canada_0-03-png\/","title":{"rendered":"Opinions on science-related issues, from AI to food to childhood vaccines"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-7395","attachment","type-attachment","status-inherit","hentry"],"filename":"PS_2020.09.29_factsheet-canada_0-03.png","filesize":142330,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png'><img loading=\"lazy\" decoding=\"async\" width=\"194\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=194\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows opinions on science-related issues, from AI to food to childhood vaccines\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=194,300 194w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=768,1190 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=661,1024 661w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=261,405 261w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=200,310 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=260,403 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=310,481 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=420,651 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=640,992 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=740,1147 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=160,248 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?resize=320,496 320w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" data-has-transparency=\"false\" data-dominant-color=\"e4e7e5\" style=\"--dominant-color: #e4e7e5;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows opinions on science-related issues, from AI to food to childhood vaccines","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1302,"file":"2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png","filesize":142330,"sizes":{"thumbnail":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=150,150","width":150,"height":150,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=150&h=150&crop=1"},"medium":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=194,300","width":194,"height":300,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=194"},"medium_large":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=768,1190","width":768,"height":1190,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=640"},"large":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=661,1024","width":661,"height":1024,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=640"},"A1":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=564,317","width":564,"height":317,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=840,634","width":840,"height":634,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=690,388","width":690,"height":388,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=840,776","width":840,"height":776,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=840&h=776&crop=1"},"A2":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=268,151","width":268,"height":151,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=536,302","width":536,"height":302,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=690,388","width":690,"height":388,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=840,776","width":840,"height":776,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=840&h=776&crop=1"},"A3":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=194,110","width":194,"height":110,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=388,220","width":388,"height":220,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=148,84","width":148,"height":84,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=296,168","width":296,"height":168,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=296&h=168&crop=1"},"A4":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=268,151","width":268,"height":151,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=536,302","width":536,"height":302,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=690,388","width":690,"height":388,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=840,776","width":840,"height":776,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=840&h=776&crop=1"},"XL":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=720,405","width":720,"height":405,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=840,810","width":840,"height":810,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=840&h=810&crop=1"},"social":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=840,628","width":840,"height":628,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=840&h=628&crop=1"},"chapter":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=261,405","width":261,"height":405,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=261"},"200-wide":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=200,310","width":200,"height":310,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=200"},"260-wide":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=260,403","width":260,"height":403,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=260"},"310-wide":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=310,481","width":310,"height":481,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=310"},"420-wide":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=420,651","width":420,"height":651,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=420"},"640-wide":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=640,992","width":640,"height":992,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=640"},"740-wide":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=740,1147","width":740,"height":1147,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=740"},"75-square":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=75,75","width":75,"height":75,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=75&h=75&crop=1"},"140-square":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=140,140","width":140,"height":140,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=140&h=140&crop=1"},"260-square":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=260,260","width":260,"height":260,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=160,248","width":160,"height":248,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=160"},"320-portrait":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=320,496","width":320,"height":496,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=320"},"200-by-133":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=200,133","width":200,"height":133,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=740,416","width":740,"height":416,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PS_2020.09.29_factsheet-canada_0-03.png?resize=540,304","width":540,"height":304,"filesize":142330,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png?w=540&h=304&crop=1"},"full":{"file":"PS_2020.09.29_factsheet-canada_0-03.png","width":840,"height":1302,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e4e7e5","has_transparency":false},"post":7336,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2020\/09\/PS_2020.09.29_factsheet-canada_0-03.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Opinions on science-related issues, from AI to food to childhood vaccines","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/7395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=7395"}],"wp:attached-to":[{"embeddable":true,"post_type":"fact-sheet","id":7336,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/fact-sheet\/7336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}