{"id":80717,"date":"2024-01-12T13:56:04","date_gmt":"2024-01-12T18:56:04","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png"},"modified":"2024-01-12T13:56:04","modified_gmt":"2024-01-12T18:56:04","slug":"pr_2024-01-24_religious_nones_3-02-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2024\/01\/24\/are-nones-less-involved-in-civic-life-than-people-who-identify-with-a-religion\/pr_2024-01-24_religious_nones_3-02-png\/","title":{"rendered":"Among \u2018nones,\u2019 atheists and agnostics tend to be more civically engaged than those who say their religion is \u2018nothing in particular\u2019"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-80717","attachment","type-attachment","status-inherit","hentry"],"filename":"PR_2024.01.24_religious_nones_3-02.png","filesize":221514,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png'><img loading=\"lazy\" decoding=\"async\" width=\"158\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=158\" class=\"attachment-medium size-medium not-transparent\" alt=\"Table shows Among \u2018nones,\u2019 atheists and agnostics tend to be more civically engaged than those who say their religion is \u2018nothing in particular\u2019\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=158,300 158w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=768,1457 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=540,1024 540w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=809,1536 809w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=213,405 213w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=200,380 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=260,493 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=310,588 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=420,797 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=640,1214 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=740,1404 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=160,304 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?resize=320,607 320w\" sizes=\"auto, (max-width: 158px) 100vw, 158px\" data-has-transparency=\"false\" data-dominant-color=\"efefef\" style=\"--dominant-color: #efefef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Table shows Among \u2018nones,\u2019 atheists and agnostics tend to be more civically engaged than those who say their religion is \u2018nothing in particular\u2019","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1594,"file":"2024\/01\/PR_2024.01.24_religious_nones_3-02.png","filesize":221514,"sizes":{"thumbnail":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=150,150","width":150,"height":150,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=150&h=150&crop=1"},"medium":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=158,300","width":158,"height":300,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=158"},"medium_large":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=768,1457","width":768,"height":1457,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=640"},"large":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=540,1024","width":540,"height":1024,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=540"},"1536x1536":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=809,1536","width":809,"height":1536,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=809"},"A1":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=564,317","width":564,"height":317,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=840,634","width":840,"height":634,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=690,388","width":690,"height":388,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=840,776","width":840,"height":776,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=840&h=776&crop=1"},"A2":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=268,151","width":268,"height":151,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=536,302","width":536,"height":302,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=690,388","width":690,"height":388,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=840,776","width":840,"height":776,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=840&h=776&crop=1"},"A3":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=194,110","width":194,"height":110,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=388,220","width":388,"height":220,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=148,84","width":148,"height":84,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=296,168","width":296,"height":168,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=296&h=168&crop=1"},"A4":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=268,151","width":268,"height":151,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=536,302","width":536,"height":302,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=690,388","width":690,"height":388,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=840,776","width":840,"height":776,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=840&h=776&crop=1"},"XL":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=720,405","width":720,"height":405,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=840,810","width":840,"height":810,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=840&h=810&crop=1"},"social":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=840,628","width":840,"height":628,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=840&h=628&crop=1"},"chapter":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=213,405","width":213,"height":405,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=213"},"200-wide":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=200,380","width":200,"height":380,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=200"},"260-wide":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=260,493","width":260,"height":493,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=260"},"310-wide":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=310,588","width":310,"height":588,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=310"},"420-wide":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=420,797","width":420,"height":797,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=420"},"640-wide":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=640,1214","width":640,"height":1214,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=640"},"740-wide":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=740,1404","width":740,"height":1404,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=740"},"75-square":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=75,75","width":75,"height":75,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=75&h=75&crop=1"},"140-square":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=140,140","width":140,"height":140,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=140&h=140&crop=1"},"260-square":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=260,260","width":260,"height":260,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=160,304","width":160,"height":304,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=160"},"320-portrait":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=320,607","width":320,"height":607,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=320"},"200-by-133":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=200,133","width":200,"height":133,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=740,416","width":740,"height":416,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PR_2024.01.24_religious_nones_3-02.png?resize=540,304","width":540,"height":304,"filesize":221514,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png?w=540&h=304&crop=1"},"full":{"file":"PR_2024.01.24_religious_nones_3-02.png","width":840,"height":1594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"efefef","has_transparency":false},"post":69503,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/PR_2024.01.24_religious_nones_3-02.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Among \u2018nones,\u2019 atheists and agnostics tend to be more civically engaged than those who say their religion is \u2018nothing in particular\u2019","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/80717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=80717"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":69503,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/69503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}