{"id":80743,"date":"2023-12-05T11:15:12","date_gmt":"2023-12-05T16:15:12","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png"},"modified":"2023-12-05T11:15:12","modified_gmt":"2023-12-05T16:15:12","slug":"pr_2023-12-07_spirituality_4-01-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2023\/12\/07\/spiritual-experiences\/pr_2023-12-07_spirituality_4-01-png\/","title":{"rendered":"45% of Americans have had a sudden feeling of connection with something from beyond this world"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-80743","attachment","type-attachment","status-inherit","hentry"],"filename":"PR_2023.12.07_spirituality_4-01.png","filesize":119352,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"213\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows 45% of Americans have had a sudden feeling of connection with something from beyond this world\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png 1280w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=300,213 300w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=768,546 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=1024,728 1024w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=570,405 570w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=200,142 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=260,185 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=310,220 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=420,299 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=640,455 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=740,526 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=160,114 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?resize=320,228 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"e2ebef\" style=\"--dominant-color: #e2ebef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows 45% of Americans have had a sudden feeling of connection with something from beyond this world","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":910,"file":"2023\/12\/PR_2023.12.07_spirituality_4-01.png","filesize":119352,"sizes":{"thumbnail":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=150,150","width":150,"height":150,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=150&h=150&crop=1"},"medium":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=300,213","width":300,"height":213,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=300"},"medium_large":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=768,546","width":768,"height":546,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=640"},"large":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1024,728","width":1024,"height":728,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=640"},"A1":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=564,317","width":564,"height":317,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1128,634","width":1128,"height":634,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=690,388","width":690,"height":388,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1280,776","width":1280,"height":776,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=1280&h=776&crop=1"},"A2":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=268,151","width":268,"height":151,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=536,302","width":536,"height":302,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=690,388","width":690,"height":388,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1280,776","width":1280,"height":776,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=1280&h=776&crop=1"},"A3":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=194,110","width":194,"height":110,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=388,220","width":388,"height":220,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=148,84","width":148,"height":84,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=296,168","width":296,"height":168,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=296&h=168&crop=1"},"A4":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=268,151","width":268,"height":151,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=536,302","width":536,"height":302,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=690,388","width":690,"height":388,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1280,776","width":1280,"height":776,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=1280&h=776&crop=1"},"XL":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=720,405","width":720,"height":405,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1280,810","width":1280,"height":810,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=1280&h=810&crop=1"},"social":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=1200,628","width":1200,"height":628,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=1200&h=628&crop=1"},"chapter":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=570,405","width":570,"height":405,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=570"},"200-wide":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=200,142","width":200,"height":142,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=200"},"260-wide":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=260,185","width":260,"height":185,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=260"},"310-wide":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=310,220","width":310,"height":220,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=310"},"420-wide":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=420,299","width":420,"height":299,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=420"},"640-wide":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=640,455","width":640,"height":455,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=640"},"740-wide":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=740,526","width":740,"height":526,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=740"},"75-square":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=75,75","width":75,"height":75,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=140,140","width":140,"height":140,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=260,260","width":260,"height":260,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=160,114","width":160,"height":114,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=160"},"320-portrait":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=320,228","width":320,"height":228,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=320"},"200-by-133":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=200,133","width":200,"height":133,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=740,416","width":740,"height":416,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PR_2023.12.07_spirituality_4-01.png?resize=540,304","width":540,"height":304,"filesize":119352,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png?w=540&h=304&crop=1"},"full":{"file":"PR_2023.12.07_spirituality_4-01.png","width":1200,"height":853,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"e2ebef","has_transparency":false},"post":69584,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/12\/PR_2023.12.07_spirituality_4-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"45% of Americans have had a sudden feeling of connection with something from beyond this world","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/80743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=80743"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":69584,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/69584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}