{"id":81415,"date":"2022-11-23T12:22:42","date_gmt":"2022-11-23T17:22:42","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png"},"modified":"2022-11-23T12:22:42","modified_gmt":"2022-11-23T17:22:42","slug":"pf_2022-11-29_religious-restrictions_00-01-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/how-covid-19-restrictions-affected-religious-groups-around-the-world-in-2020\/pf_2022-11-29_religious-restrictions_00-01-png\/","title":{"rendered":"In 74 countries, religious groups faced force, blame related to COVID-19 pandemic in 2020"},"author":581,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-81415","attachment","type-attachment","status-inherit","hentry"],"filename":"PF_2022.11.29_religious-restrictions_00-01.png","filesize":323863,"_embeds":[],"table_of_contents":[{"id":70155,"title":"How COVID-19 Restrictions Affected Religious Groups Around the World in 2020","slug":"how-covid-19-restrictions-affected-religious-groups-around-the-world-in-2020","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/how-covid-19-restrictions-affected-religious-groups-around-the-world-in-2020\/","is_active":false},{"id":70186,"title":"1. Number of countries with \u2018very high\u2019 government restrictions falls for third straight year in 2020","slug":"number-of-countries-with-very-high-government-restrictions-falls-for-third-straight-year-in-2020","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/number-of-countries-with-very-high-government-restrictions-falls-for-third-straight-year-in-2020\/","is_active":false},{"id":70178,"title":"2. Physical harassment related to religion occurred in more than two-thirds of countries in 2020","slug":"physical-harassment-related-to-religion-occurred-in-more-than-two-thirds-of-countries-in-2020","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/physical-harassment-related-to-religion-occurred-in-more-than-two-thirds-of-countries-in-2020\/","is_active":false},{"id":70171,"title":"3. Small changes in median scores for government restrictions, social hostilities involving religion in 2020","slug":"small-changes-in-median-scores-for-government-restrictions-social-hostilities-involving-religion-in-2020","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/small-changes-in-median-scores-for-government-restrictions-social-hostilities-involving-religion-in-2020\/","is_active":false},{"id":70166,"title":"4. Restrictions in the 25 most populous countries","slug":"restrictions-in-the-25-most-populous-countries","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/restrictions-in-the-25-most-populous-countries\/","is_active":false},{"id":70174,"title":"Acknowledgments","slug":"restrictions-2022-acknowledgments","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/restrictions-2022-acknowledgments\/","is_active":false},{"id":70143,"title":"Methodology","slug":"restrictions-2022-methodology","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2022\/11\/29\/restrictions-2022-methodology\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png'><img loading=\"lazy\" decoding=\"async\" width=\"287\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=287\" class=\"attachment-medium size-medium not-transparent\" alt=\"Chart shows in 74 countries, religious groups faced force, blame related to COVID-19 pandemic in 2020\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=287,300 287w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=768,803 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=387,405 387w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=200,209 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=260,272 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=310,324 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=420,439 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=640,669 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=740,773 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=160,167 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?resize=320,334 320w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" data-has-transparency=\"false\" data-dominant-color=\"eaebea\" style=\"--dominant-color: #eaebea;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Chart shows in 74 countries, religious groups faced force, blame related to COVID-19 pandemic in 2020","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":878,"file":"2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png","filesize":323863,"sizes":{"thumbnail":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=150,150","width":150,"height":150,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=150&h=150&crop=1"},"medium":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=287,300","width":287,"height":300,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=287"},"medium_large":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=768,803","width":768,"height":803,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=640"},"A1":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=564,317","width":564,"height":317,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=840,634","width":840,"height":634,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=690,388","width":690,"height":388,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=840,776","width":840,"height":776,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=840&h=776&crop=1"},"A2":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=268,151","width":268,"height":151,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=536,302","width":536,"height":302,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=690,388","width":690,"height":388,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=840,776","width":840,"height":776,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=840&h=776&crop=1"},"A3":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=194,110","width":194,"height":110,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=388,220","width":388,"height":220,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=148,84","width":148,"height":84,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=296,168","width":296,"height":168,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=296&h=168&crop=1"},"A4":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=268,151","width":268,"height":151,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=536,302","width":536,"height":302,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=690,388","width":690,"height":388,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=840,776","width":840,"height":776,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=840&h=776&crop=1"},"XL":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=720,405","width":720,"height":405,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=840,810","width":840,"height":810,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=840&h=810&crop=1"},"social":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=840,628","width":840,"height":628,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=840&h=628&crop=1"},"chapter":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=387,405","width":387,"height":405,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=387"},"200-wide":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=200,209","width":200,"height":209,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=200"},"260-wide":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=260,272","width":260,"height":272,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=260"},"310-wide":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=310,324","width":310,"height":324,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=310"},"420-wide":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=420,439","width":420,"height":439,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=420"},"640-wide":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=640,669","width":640,"height":669,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=640"},"740-wide":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=740,773","width":740,"height":773,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=740"},"75-square":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=75,75","width":75,"height":75,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=140,140","width":140,"height":140,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=260,260","width":260,"height":260,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=160,167","width":160,"height":167,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=160"},"320-portrait":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=320,334","width":320,"height":334,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=320"},"200-by-133":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=200,133","width":200,"height":133,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=740,416","width":740,"height":416,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=740&h=416&crop=1"},"540-by-304":{"file":"PF_2022.11.29_religious-restrictions_00-01.png?resize=540,304","width":540,"height":304,"filesize":323863,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png?w=540&h=304&crop=1"},"full":{"file":"PF_2022.11.29_religious-restrictions_00-01.png","width":840,"height":878,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eaebea","has_transparency":false},"post":70155,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2022\/11\/PF_2022.11.29_religious-restrictions_00-01.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"In 74 countries, religious groups faced force, blame related to COVID-19 pandemic in 2020","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/81415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/581"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=81415"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":70155,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/70155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}