{"id":83591,"date":"2017-11-22T09:47:16","date_gmt":"2017-11-22T14:47:16","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png"},"modified":"2017-11-22T09:47:16","modified_gmt":"2017-11-22T14:47:16","slug":"pf_11-29-17_muslims-update-14-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2017\/11\/29\/europes-growing-muslim-population\/pf_11-29-17_muslims-update-14-png\/","title":{"rendered":"The size of the European Muslim population in 2050 depends largely on the future of migration"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-83591","attachment","type-attachment","status-inherit","hentry"],"filename":"PF_11.29.17_muslims-update-14.png","filesize":21259,"_embeds":[],"table_of_contents":[{"id":71733,"title":"Europe\u2019s Growing Muslim Population","slug":"europes-growing-muslim-population","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2017\/11\/29\/europes-growing-muslim-population\/","is_active":false},{"id":71669,"title":"Acknowledgments","slug":"acknowledgments-europes-muslim-population","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2017\/11\/29\/acknowledgments-europes-muslim-population\/","is_active":false},{"id":71721,"title":"Appendix A: Methodology","slug":"appendix-a-methodology-europes-muslim-population","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2017\/11\/29\/appendix-a-methodology-europes-muslim-population\/","is_active":false}],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png'><img loading=\"lazy\" decoding=\"async\" width=\"153\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=153\" class=\"attachment-medium size-medium not-transparent\" alt=\"The size of the European Muslim population in 2050 depends largely on the future of migration\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=153,300 153w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=206,405 206w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=200,392 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=260,510 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=310,608 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=160,314 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?resize=320,628 320w\" sizes=\"auto, (max-width: 153px) 100vw, 153px\" data-has-transparency=\"false\" data-dominant-color=\"f1f1f1\" style=\"--dominant-color: #f1f1f1;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"The size of the European Muslim population in 2050 depends largely on the future of migration","media_type":"image","mime_type":"image\/png","media_details":{"width":420,"height":824,"file":"2017\/11\/PF_11.29.17_muslims-update-14.png","filesize":21259,"sizes":{"thumbnail":{"file":"PF_11.29.17_muslims-update-14.png?resize=150,150","width":150,"height":150,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=150&h=150&crop=1"},"medium":{"file":"PF_11.29.17_muslims-update-14.png?resize=153,300","width":153,"height":300,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=153"},"A1":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,317","width":420,"height":317,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=317&crop=1"},"A1-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,634","width":420,"height":634,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=634&crop=1"},"A1-SMALL":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,388","width":420,"height":388,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,776","width":420,"height":776,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=776&crop=1"},"A2":{"file":"PF_11.29.17_muslims-update-14.png?resize=268,151","width":268,"height":151,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,302","width":420,"height":302,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=302&crop=1"},"A2-SMALL":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,388","width":420,"height":388,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,776","width":420,"height":776,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=776&crop=1"},"A3":{"file":"PF_11.29.17_muslims-update-14.png?resize=194,110","width":194,"height":110,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=388,220","width":388,"height":220,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"PF_11.29.17_muslims-update-14.png?resize=148,84","width":148,"height":84,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=296,168","width":296,"height":168,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=296&h=168&crop=1"},"A4":{"file":"PF_11.29.17_muslims-update-14.png?resize=268,151","width":268,"height":151,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,302","width":420,"height":302,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=302&crop=1"},"A4-SMALL":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,388","width":420,"height":388,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,776","width":420,"height":776,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=776&crop=1"},"XL":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,405","width":420,"height":405,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=405&crop=1"},"XL-HIDPI":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,810","width":420,"height":810,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=810&crop=1"},"social":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,628","width":420,"height":628,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=628&crop=1"},"chapter":{"file":"PF_11.29.17_muslims-update-14.png?resize=206,405","width":206,"height":405,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=206"},"200-wide":{"file":"PF_11.29.17_muslims-update-14.png?resize=200,392","width":200,"height":392,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=200"},"260-wide":{"file":"PF_11.29.17_muslims-update-14.png?resize=260,510","width":260,"height":510,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=260"},"310-wide":{"file":"PF_11.29.17_muslims-update-14.png?resize=310,608","width":310,"height":608,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=310"},"75-square":{"file":"PF_11.29.17_muslims-update-14.png?resize=75,75","width":75,"height":75,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_11.29.17_muslims-update-14.png?resize=140,140","width":140,"height":140,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_11.29.17_muslims-update-14.png?resize=260,260","width":260,"height":260,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=260&h=260&crop=1"},"160-portrait":{"file":"PF_11.29.17_muslims-update-14.png?resize=160,314","width":160,"height":314,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=160"},"320-portrait":{"file":"PF_11.29.17_muslims-update-14.png?resize=320,628","width":320,"height":628,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=320"},"200-by-133":{"file":"PF_11.29.17_muslims-update-14.png?resize=200,133","width":200,"height":133,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=200&h=133&crop=1"},"740-by-416":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,416","width":420,"height":416,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=416&crop=1"},"540-by-304":{"file":"PF_11.29.17_muslims-update-14.png?resize=420,304","width":420,"height":304,"filesize":21259,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png?w=420&h=304&crop=1"},"full":{"file":"PF_11.29.17_muslims-update-14.png","width":420,"height":824,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f1f1f1","has_transparency":false},"post":71733,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2017\/11\/PF_11.29.17_muslims-update-14.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"The size of the European Muslim population in 2050 depends largely on the future of migration","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/83591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=83591"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":71733,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/71733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}