{"id":83657,"date":"2018-05-23T10:51:53","date_gmt":"2018-05-23T15:51:53","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png"},"modified":"2018-05-23T10:51:53","modified_gmt":"2018-05-23T15:51:53","slug":"pf_05-29-18_religion-western-europe-03-01-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/religion\/2018\/05\/29\/religious-practice-and-belief\/pf_05-29-18_religion-western-europe-03-01-png\/","title":{"rendered":"Fully seven-in-ten in Denmark, Sweden say religion is not important to them"},"author":367,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-83657","attachment","type-attachment","status-inherit","hentry"],"filename":"PF_05.29.18_religion.western.europe-03-01-.png","filesize":10179,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png'><img loading=\"lazy\" decoding=\"async\" width=\"101\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=101\" class=\"attachment-medium size-medium not-transparent\" alt=\"Fully seven-in-ten in Denmark, Sweden say religion is not important to them\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png 199w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?resize=101,300 101w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?resize=136,405 136w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?resize=108,320 108w\" sizes=\"auto, (max-width: 101px) 100vw, 101px\" data-has-transparency=\"false\" data-dominant-color=\"ededed\" style=\"--dominant-color: #ededed;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Fully seven-in-ten in Denmark, Sweden say religion is not important to them","media_type":"image","mime_type":"image\/png","media_details":{"width":199,"height":591,"file":"2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png","filesize":10179,"sizes":{"thumbnail":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=150,150","width":150,"height":150,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=150&h=150&crop=1"},"medium":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=101,300","width":101,"height":300,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=101"},"A1":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,317","width":199,"height":317,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=317&crop=1"},"A1-SMALL":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,388","width":199,"height":388,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=388&crop=1"},"A2":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,151","width":199,"height":151,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=151&crop=1"},"A2-HIDPI":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,302","width":199,"height":302,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=302&crop=1"},"A2-SMALL":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,388","width":199,"height":388,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=388&crop=1"},"A3":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=194,110","width":194,"height":110,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,220","width":199,"height":220,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=220&crop=1"},"A3-SMALL":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=148,84","width":148,"height":84,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,168","width":199,"height":168,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=168&crop=1"},"A4":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,151","width":199,"height":151,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=151&crop=1"},"A4-HIDPI":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,302","width":199,"height":302,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=302&crop=1"},"A4-SMALL":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,388","width":199,"height":388,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=388&crop=1"},"XL":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,405","width":199,"height":405,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=405&crop=1"},"chapter":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=136,405","width":136,"height":405,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=136"},"75-square":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=75,75","width":75,"height":75,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=75&h=75&crop=1"},"140-square":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=140,140","width":140,"height":140,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=140&h=140&crop=1"},"260-square":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,260","width":199,"height":260,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=260&crop=1"},"160-portrait":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=108,320","width":108,"height":320,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=108"},"200-by-133":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,133","width":199,"height":133,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=133&crop=1"},"740-by-416":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,416","width":199,"height":416,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=416&crop=1"},"540-by-304":{"file":"PF_05.29.18_religion.western.europe-03-01-.png?resize=199,304","width":199,"height":304,"filesize":10179,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png?w=199&h=304&crop=1"},"full":{"file":"PF_05.29.18_religion.western.europe-03-01-.png","width":199,"height":591,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"ededed","has_transparency":false},"post":71765,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2018\/05\/PF_05.29.18_religion.western.europe-03-01-.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Fully seven-in-ten in Denmark, Sweden say religion is not important to them","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/83657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/367"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=83657"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":71765,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/posts\/71765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}