{"id":8377,"date":"2024-04-01T11:51:58","date_gmt":"2024-04-01T16:51:58","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png"},"modified":"2024-04-01T11:51:58","modified_gmt":"2024-04-01T16:51:58","slug":"sr_24-04-02_muslims-views-of-war_7-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2024\/04\/02\/how-us-muslims-are-experiencing-the-israel-hamas-war\/sr_24-04-02_muslims-views-of-war_7-png\/","title":{"rendered":"About half of U.S. Muslims say news about the Israel-Hamas war makes them feel afraid"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-8377","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_24.04.02_muslims-views-of-war_7.png","filesize":73704,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png'><img loading=\"lazy\" decoding=\"async\" width=\"237\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=237\" class=\"attachment-medium size-medium not-transparent\" alt=\"A dot plot showing that about half of U.S. Muslims say news about the Israel-Hamas war makes them feel afraid.\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png 620w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=237,300 237w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=320,405 320w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=200,253 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=260,329 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=310,392 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=420,531 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?resize=160,202 160w\" sizes=\"auto, (max-width: 237px) 100vw, 237px\" data-has-transparency=\"false\" data-dominant-color=\"f1f1f1\" style=\"--dominant-color: #f1f1f1;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A dot plot showing that about half of U.S. Muslims say news about the Israel-Hamas war makes them feel afraid.","media_type":"image","mime_type":"image\/png","media_details":{"width":620,"height":784,"file":"2024\/04\/SR_24.04.02_muslims-views-of-war_7.png","filesize":73704,"sizes":{"thumbnail":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=150,150","width":150,"height":150,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=150&h=150&crop=1"},"medium":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=237,300","width":237,"height":300,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=237"},"A1":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=564,317","width":564,"height":317,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,634","width":620,"height":634,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=634&crop=1"},"A1-SMALL":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,388","width":620,"height":388,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,776","width":620,"height":776,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=776&crop=1"},"A2":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=268,151","width":268,"height":151,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=536,302","width":536,"height":302,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,388","width":620,"height":388,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,776","width":620,"height":776,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=776&crop=1"},"A3":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=194,110","width":194,"height":110,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=388,220","width":388,"height":220,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=148,84","width":148,"height":84,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=296,168","width":296,"height":168,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=296&h=168&crop=1"},"A4":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=268,151","width":268,"height":151,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=536,302","width":536,"height":302,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,388","width":620,"height":388,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,776","width":620,"height":776,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=776&crop=1"},"XL":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,405","width":620,"height":405,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=405&crop=1"},"social":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,628","width":620,"height":628,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=628&crop=1"},"chapter":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=320,405","width":320,"height":405,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=320"},"200-wide":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=200,253","width":200,"height":253,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=200"},"260-wide":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=260,329","width":260,"height":329,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=260"},"310-wide":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=310,392","width":310,"height":392,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=310"},"420-wide":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=420,531","width":420,"height":531,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=420"},"75-square":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=75,75","width":75,"height":75,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=140,140","width":140,"height":140,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=260,260","width":260,"height":260,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=160,202","width":160,"height":202,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=160"},"320-portrait":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=320,405","width":320,"height":405,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=320"},"200-by-133":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=200,133","width":200,"height":133,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=620,416","width":620,"height":416,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=620&h=416&crop=1"},"540-by-304":{"file":"SR_24.04.02_muslims-views-of-war_7.png?resize=540,304","width":540,"height":304,"filesize":73704,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png?w=540&h=304&crop=1"},"full":{"file":"SR_24.04.02_muslims-views-of-war_7.png","width":620,"height":784,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f1f1f1","has_transparency":false},"post":7767,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/04\/SR_24.04.02_muslims-views-of-war_7.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"About half of U.S. Muslims say news about the Israel-Hamas war makes them feel afraid","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/8377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=8377"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":7767,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/7767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}