{"id":9034,"date":"2023-11-16T10:43:34","date_gmt":"2023-11-16T15:43:34","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png"},"modified":"2023-11-16T10:43:34","modified_gmt":"2023-11-16T15:43:34","slug":"sr_23-11-17_bullying_2-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2023\/11\/17\/9-facts-about-bullying-in-the-us\/sr_23-11-17_bullying_2-png\/","title":{"rendered":"Nearly half of teens have ever experienced cyberbullying, with offensive name-calling being the type most commonly reported"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-9034","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_23.11.17_Bullying_2.png","filesize":146449,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png'><img loading=\"lazy\" decoding=\"async\" width=\"235\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=235\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that nearly half of teens have ever experienced cyberbullying, with offensive name-calling being the type most commonly reported.\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=235,300 235w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=768,980 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=802,1024 802w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=317,405 317w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=200,255 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=260,332 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=310,396 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=420,536 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=640,817 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=740,944 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=160,204 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?resize=320,408 320w\" sizes=\"auto, (max-width: 235px) 100vw, 235px\" data-has-transparency=\"false\" data-dominant-color=\"d4dae0\" style=\"--dominant-color: #d4dae0;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that nearly half of teens have ever experienced cyberbullying, with offensive name-calling being the type most commonly reported.","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1072,"file":"2023\/11\/SR_23.11.17_Bullying_2.png","filesize":146449,"sizes":{"thumbnail":{"file":"SR_23.11.17_Bullying_2.png?resize=150,150","width":150,"height":150,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=150&h=150&crop=1"},"medium":{"file":"SR_23.11.17_Bullying_2.png?resize=235,300","width":235,"height":300,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=235"},"medium_large":{"file":"SR_23.11.17_Bullying_2.png?resize=768,980","width":768,"height":980,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=640"},"large":{"file":"SR_23.11.17_Bullying_2.png?resize=802,1024","width":802,"height":1024,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=640"},"A1":{"file":"SR_23.11.17_Bullying_2.png?resize=564,317","width":564,"height":317,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=840,634","width":840,"height":634,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"SR_23.11.17_Bullying_2.png?resize=690,388","width":690,"height":388,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=840,776","width":840,"height":776,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=840&h=776&crop=1"},"A2":{"file":"SR_23.11.17_Bullying_2.png?resize=268,151","width":268,"height":151,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=536,302","width":536,"height":302,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_23.11.17_Bullying_2.png?resize=690,388","width":690,"height":388,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=840,776","width":840,"height":776,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=840&h=776&crop=1"},"A3":{"file":"SR_23.11.17_Bullying_2.png?resize=194,110","width":194,"height":110,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=388,220","width":388,"height":220,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_23.11.17_Bullying_2.png?resize=148,84","width":148,"height":84,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=296,168","width":296,"height":168,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=296&h=168&crop=1"},"A4":{"file":"SR_23.11.17_Bullying_2.png?resize=268,151","width":268,"height":151,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=536,302","width":536,"height":302,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_23.11.17_Bullying_2.png?resize=690,388","width":690,"height":388,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=840,776","width":840,"height":776,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=840&h=776&crop=1"},"XL":{"file":"SR_23.11.17_Bullying_2.png?resize=720,405","width":720,"height":405,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_23.11.17_Bullying_2.png?resize=840,810","width":840,"height":810,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=840&h=810&crop=1"},"social":{"file":"SR_23.11.17_Bullying_2.png?resize=840,628","width":840,"height":628,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=840&h=628&crop=1"},"chapter":{"file":"SR_23.11.17_Bullying_2.png?resize=317,405","width":317,"height":405,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=317"},"200-wide":{"file":"SR_23.11.17_Bullying_2.png?resize=200,255","width":200,"height":255,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=200"},"260-wide":{"file":"SR_23.11.17_Bullying_2.png?resize=260,332","width":260,"height":332,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=260"},"310-wide":{"file":"SR_23.11.17_Bullying_2.png?resize=310,396","width":310,"height":396,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=310"},"420-wide":{"file":"SR_23.11.17_Bullying_2.png?resize=420,536","width":420,"height":536,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=420"},"640-wide":{"file":"SR_23.11.17_Bullying_2.png?resize=640,817","width":640,"height":817,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=640"},"740-wide":{"file":"SR_23.11.17_Bullying_2.png?resize=740,944","width":740,"height":944,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=740"},"75-square":{"file":"SR_23.11.17_Bullying_2.png?resize=75,75","width":75,"height":75,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_23.11.17_Bullying_2.png?resize=140,140","width":140,"height":140,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_23.11.17_Bullying_2.png?resize=260,260","width":260,"height":260,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_23.11.17_Bullying_2.png?resize=160,204","width":160,"height":204,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=160"},"320-portrait":{"file":"SR_23.11.17_Bullying_2.png?resize=320,408","width":320,"height":408,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=320"},"200-by-133":{"file":"SR_23.11.17_Bullying_2.png?resize=200,133","width":200,"height":133,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_23.11.17_Bullying_2.png?resize=740,416","width":740,"height":416,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_23.11.17_Bullying_2.png?resize=540,304","width":540,"height":304,"filesize":146449,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png?w=540&h=304&crop=1"},"full":{"file":"SR_23.11.17_Bullying_2.png","width":840,"height":1072,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"d4dae0","has_transparency":false},"post":7834,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/11\/SR_23.11.17_Bullying_2.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Nearly half of teens have ever experienced cyberbullying, with offensive name-calling being the type most commonly reported","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/9034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=9034"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":7834,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/7834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}