{"id":9116,"date":"2024-01-02T22:40:04","date_gmt":"2024-01-03T03:40:04","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png"},"modified":"2024-01-02T22:40:04","modified_gmt":"2024-01-03T03:40:04","slug":"sr_2024-01-03_dry-january_04-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2024\/01\/03\/10-facts-about-americans-and-alcohol-as-dry-january-begins\/sr_2024-01-03_dry-january_04-png\/","title":{"rendered":"Year after year, December is the peak month for U.S. retail alcohol sales"},"author":648,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-9116","attachment","type-attachment","status-inherit","hentry"],"filename":"sr_2024.01.03_dry-january_04.png","filesize":72706,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png'><img loading=\"lazy\" decoding=\"async\" width=\"246\" height=\"300\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=246\" class=\"attachment-medium size-medium not-transparent\" alt=\"A line chart showing that year after year, December is the peak month for U.S. retail alcohol sales\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png 840w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=246,300 246w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=768,938 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=838,1024 838w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=332,405 332w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=200,244 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=260,318 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=310,379 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=420,513 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=640,782 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=740,904 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=160,195 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?resize=320,391 320w\" sizes=\"auto, (max-width: 246px) 100vw, 246px\" data-has-transparency=\"false\" data-dominant-color=\"f1f3f3\" style=\"--dominant-color: #f1f3f3;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A line chart showing that year after year, December is the peak month for U.S. retail alcohol sales","media_type":"image","mime_type":"image\/png","media_details":{"width":840,"height":1026,"file":"2024\/01\/sr_2024.01.03_dry-january_04.png","filesize":72706,"sizes":{"thumbnail":{"file":"sr_2024.01.03_dry-january_04.png?resize=150,150","width":150,"height":150,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=150&h=150&crop=1"},"medium":{"file":"sr_2024.01.03_dry-january_04.png?resize=246,300","width":246,"height":300,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=246"},"medium_large":{"file":"sr_2024.01.03_dry-january_04.png?resize=768,938","width":768,"height":938,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=640"},"large":{"file":"sr_2024.01.03_dry-january_04.png?resize=838,1024","width":838,"height":1024,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=640"},"A1":{"file":"sr_2024.01.03_dry-january_04.png?resize=564,317","width":564,"height":317,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=840,634","width":840,"height":634,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=840&h=634&crop=1"},"A1-SMALL":{"file":"sr_2024.01.03_dry-january_04.png?resize=690,388","width":690,"height":388,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=840,776","width":840,"height":776,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=840&h=776&crop=1"},"A2":{"file":"sr_2024.01.03_dry-january_04.png?resize=268,151","width":268,"height":151,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=536,302","width":536,"height":302,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"sr_2024.01.03_dry-january_04.png?resize=690,388","width":690,"height":388,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=840,776","width":840,"height":776,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=840&h=776&crop=1"},"A3":{"file":"sr_2024.01.03_dry-january_04.png?resize=194,110","width":194,"height":110,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=388,220","width":388,"height":220,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"sr_2024.01.03_dry-january_04.png?resize=148,84","width":148,"height":84,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=296,168","width":296,"height":168,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=296&h=168&crop=1"},"A4":{"file":"sr_2024.01.03_dry-january_04.png?resize=268,151","width":268,"height":151,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=536,302","width":536,"height":302,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"sr_2024.01.03_dry-january_04.png?resize=690,388","width":690,"height":388,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=840,776","width":840,"height":776,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=840&h=776&crop=1"},"XL":{"file":"sr_2024.01.03_dry-january_04.png?resize=720,405","width":720,"height":405,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"sr_2024.01.03_dry-january_04.png?resize=840,810","width":840,"height":810,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=840&h=810&crop=1"},"social":{"file":"sr_2024.01.03_dry-january_04.png?resize=840,628","width":840,"height":628,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=840&h=628&crop=1"},"chapter":{"file":"sr_2024.01.03_dry-january_04.png?resize=332,405","width":332,"height":405,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=332"},"200-wide":{"file":"sr_2024.01.03_dry-january_04.png?resize=200,244","width":200,"height":244,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=200"},"260-wide":{"file":"sr_2024.01.03_dry-january_04.png?resize=260,318","width":260,"height":318,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=260"},"310-wide":{"file":"sr_2024.01.03_dry-january_04.png?resize=310,379","width":310,"height":379,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=310"},"420-wide":{"file":"sr_2024.01.03_dry-january_04.png?resize=420,513","width":420,"height":513,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=420"},"640-wide":{"file":"sr_2024.01.03_dry-january_04.png?resize=640,782","width":640,"height":782,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=640"},"740-wide":{"file":"sr_2024.01.03_dry-january_04.png?resize=740,904","width":740,"height":904,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=740"},"75-square":{"file":"sr_2024.01.03_dry-january_04.png?resize=75,75","width":75,"height":75,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=75&h=75&crop=1"},"140-square":{"file":"sr_2024.01.03_dry-january_04.png?resize=140,140","width":140,"height":140,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=140&h=140&crop=1"},"260-square":{"file":"sr_2024.01.03_dry-january_04.png?resize=260,260","width":260,"height":260,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=260&h=260&crop=1"},"160-portrait":{"file":"sr_2024.01.03_dry-january_04.png?resize=160,195","width":160,"height":195,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=160"},"320-portrait":{"file":"sr_2024.01.03_dry-january_04.png?resize=320,391","width":320,"height":391,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=320"},"200-by-133":{"file":"sr_2024.01.03_dry-january_04.png?resize=200,133","width":200,"height":133,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=200&h=133&crop=1"},"740-by-416":{"file":"sr_2024.01.03_dry-january_04.png?resize=740,416","width":740,"height":416,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=740&h=416&crop=1"},"540-by-304":{"file":"sr_2024.01.03_dry-january_04.png?resize=540,304","width":540,"height":304,"filesize":72706,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png?w=540&h=304&crop=1"},"full":{"file":"sr_2024.01.03_dry-january_04.png","width":840,"height":1026,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"f1f3f3","has_transparency":false},"post":7837,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2024\/01\/sr_2024.01.03_dry-january_04.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Year after year, December is the peak month for U.S. retail alcohol sales","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/9116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/648"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=9116"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":7837,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/7837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}