{"id":9359,"date":"2023-09-06T10:39:57","date_gmt":"2023-09-06T15:39:57","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png"},"modified":"2023-09-06T10:39:57","modified_gmt":"2023-09-06T15:39:57","slug":"sr_23-09-07_religion-tech_1-png","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2023\/09\/06\/why-some-americans-prefer-to-go-to-religious-services-in-person-and-others-prefer-to-watch-virtually\/sr_23-09-07_religion-tech_1-png\/","title":{"rendered":"Sense of connection and community most popular reason why Americans prefer attending services in person over participating virtually"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-9359","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_23.09.07_religion-tech_1.png","filesize":93594,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"193\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"A bar chart showing that a sense of connection and community most popular reason why Americans prefer attending services in person over participating virtually.\" srcset=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png 1280w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=300,193 300w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=768,494 768w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=1024,659 1024w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=629,405 629w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=200,129 200w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=260,167 260w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=310,200 310w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=420,270 420w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=640,412 640w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=740,476 740w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=160,103 160w, https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?resize=320,206 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-has-transparency=\"false\" data-dominant-color=\"eaeeef\" style=\"--dominant-color: #eaeeef;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"A bar chart showing that a sense of connection and community most popular reason why Americans prefer attending services in person over participating virtually.","media_type":"image","mime_type":"image\/png","media_details":{"width":1280,"height":824,"file":"2023\/09\/SR_23.09.07_religion-tech_1.png","filesize":93594,"sizes":{"thumbnail":{"file":"SR_23.09.07_religion-tech_1.png?resize=150,150","width":150,"height":150,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=150&h=150&crop=1"},"medium":{"file":"SR_23.09.07_religion-tech_1.png?resize=300,193","width":300,"height":193,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=300"},"medium_large":{"file":"SR_23.09.07_religion-tech_1.png?resize=768,494","width":768,"height":494,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=640"},"large":{"file":"SR_23.09.07_religion-tech_1.png?resize=1024,659","width":1024,"height":659,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=640"},"A1":{"file":"SR_23.09.07_religion-tech_1.png?resize=564,317","width":564,"height":317,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=1128,634","width":1128,"height":634,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"SR_23.09.07_religion-tech_1.png?resize=690,388","width":690,"height":388,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=690&h=388&crop=1"},"A1-SMALL-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=1280,776","width":1280,"height":776,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=1280&h=776&crop=1"},"A2":{"file":"SR_23.09.07_religion-tech_1.png?resize=268,151","width":268,"height":151,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=536,302","width":536,"height":302,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_23.09.07_religion-tech_1.png?resize=690,388","width":690,"height":388,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=690&h=388&crop=1"},"A2-SMALL-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=1280,776","width":1280,"height":776,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=1280&h=776&crop=1"},"A3":{"file":"SR_23.09.07_religion-tech_1.png?resize=194,110","width":194,"height":110,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=388,220","width":388,"height":220,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_23.09.07_religion-tech_1.png?resize=148,84","width":148,"height":84,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=296,168","width":296,"height":168,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=296&h=168&crop=1"},"A4":{"file":"SR_23.09.07_religion-tech_1.png?resize=268,151","width":268,"height":151,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=536,302","width":536,"height":302,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_23.09.07_religion-tech_1.png?resize=690,388","width":690,"height":388,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=690&h=388&crop=1"},"A4-SMALL-SHIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=1280,776","width":1280,"height":776,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=1280&h=776&crop=1"},"XL":{"file":"SR_23.09.07_religion-tech_1.png?resize=720,405","width":720,"height":405,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=720&h=405&crop=1"},"XL-HIDPI":{"file":"SR_23.09.07_religion-tech_1.png?resize=1280,810","width":1280,"height":810,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=1280&h=810&crop=1"},"social":{"file":"SR_23.09.07_religion-tech_1.png?resize=1200,628","width":1200,"height":628,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=1200&h=628&crop=1"},"chapter":{"file":"SR_23.09.07_religion-tech_1.png?resize=629,405","width":629,"height":405,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=629"},"200-wide":{"file":"SR_23.09.07_religion-tech_1.png?resize=200,129","width":200,"height":129,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=200"},"260-wide":{"file":"SR_23.09.07_religion-tech_1.png?resize=260,167","width":260,"height":167,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=260"},"310-wide":{"file":"SR_23.09.07_religion-tech_1.png?resize=310,200","width":310,"height":200,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=310"},"420-wide":{"file":"SR_23.09.07_religion-tech_1.png?resize=420,270","width":420,"height":270,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=420"},"640-wide":{"file":"SR_23.09.07_religion-tech_1.png?resize=640,412","width":640,"height":412,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=640"},"740-wide":{"file":"SR_23.09.07_religion-tech_1.png?resize=740,476","width":740,"height":476,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=740"},"75-square":{"file":"SR_23.09.07_religion-tech_1.png?resize=75,75","width":75,"height":75,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=75&h=75&crop=1"},"140-square":{"file":"SR_23.09.07_religion-tech_1.png?resize=140,140","width":140,"height":140,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=140&h=140&crop=1"},"260-square":{"file":"SR_23.09.07_religion-tech_1.png?resize=260,260","width":260,"height":260,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_23.09.07_religion-tech_1.png?resize=160,103","width":160,"height":103,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=160"},"320-portrait":{"file":"SR_23.09.07_religion-tech_1.png?resize=320,206","width":320,"height":206,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=320"},"200-by-133":{"file":"SR_23.09.07_religion-tech_1.png?resize=200,133","width":200,"height":133,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_23.09.07_religion-tech_1.png?resize=740,416","width":740,"height":416,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_23.09.07_religion-tech_1.png?resize=540,304","width":540,"height":304,"filesize":93594,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png?w=540&h=304&crop=1"},"full":{"file":"SR_23.09.07_religion-tech_1.png","width":1200,"height":773,"mime_type":"image\/png","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"dominant_color":"eaeeef","has_transparency":false},"post":7910,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/09\/SR_23.09.07_religion-tech_1.png","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Sense of connection and community most popular reason why Americans prefer attending services in person over participating virtually","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/9359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=9359"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":7910,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/7910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}