{"id":9901,"date":"2023-05-16T09:14:24","date_gmt":"2023-05-16T14:14:24","guid":{"rendered":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg"},"modified":"2023-05-16T09:14:24","modified_gmt":"2023-05-16T14:14:24","slug":"sr_23-05-15_presidentialrematches_feature-jpg","status":"inherit","type":"attachment","link":"https:\/\/beta.pewresearch.org\/pewresearch-org\/short-reads\/2023\/05\/16\/a-biden-trump-faceoff-in-2024-wouldnt-be-the-first-presidential-rematch\/sr_23-05-15_presidentialrematches_feature-jpg\/","title":{"rendered":"Former President Donald Trump Rallies For Marco Rubio In Florida"},"author":658,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"sub_headline":"","sub_title":"","_prc_public_revisions":[],"_ppp_expiration_hours":0,"_ppp_enabled":false,"ai_generated_summary":"","prc_hide_media":false,"datacite_doi":"","datacite_doi_citation":"","_prc_workspace_id":0},"class_list":["post-9901","attachment","type-attachment","status-inherit","hentry"],"filename":"SR_23.05.15_PresidentialRematches_feature.jpg","filesize":104812,"_embeds":[],"table_of_contents":[],"datacite_doi":"","prepublish_checks":{},"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature-jpg.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=300\" class=\"attachment-medium size-medium not-transparent\" alt=\"Former President Donald Trump watches a video of President Joe Biden during a rally for Republican Sen. Marco Rubio at the Miami-Dade County Fair and Exposition on Nov. 6, 2022, in Miami. (Joe Raedle\/Getty Images)\" data-has-transparency=\"false\" data-dominant-color=\"493d44\" style=\"--dominant-color: #493d44;\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Former President Donald Trump watches a video of President Joe Biden during a rally for Republican Sen. Marco Rubio at the Miami-Dade County Fair and Exposition on Nov. 6, 2022, in Miami. (Joe Raedle\/Getty Images)","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":720,"file":"2023\/05\/SR_23.05.15_PresidentialRematches_feature-jpg.webp","filesize":104812,"sizes":{"thumbnail":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=150,150","width":150,"height":150,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=150&h=150&crop=1"},"medium":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=300,169","width":300,"height":169,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=300"},"medium_large":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=768,432","width":768,"height":432,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=640"},"large":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=1024,576","width":1024,"height":576,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=640"},"A1":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=564,317","width":564,"height":317,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=564&h=317&crop=1"},"A1-HIDPI":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=1128,634","width":1128,"height":634,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=1128&h=634&crop=1"},"A1-SMALL":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=690,388","width":690,"height":388,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=690&h=388&crop=1"},"A2":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=268,151","width":268,"height":151,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=268&h=151&crop=1"},"A2-HIDPI":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=536,302","width":536,"height":302,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=536&h=302&crop=1"},"A2-SMALL":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=690,388","width":690,"height":388,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=690&h=388&crop=1"},"A3":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=194,110","width":194,"height":110,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=194&h=110&crop=1"},"A3-HIDPI":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=388,220","width":388,"height":220,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=388&h=220&crop=1"},"A3-SMALL":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=148,84","width":148,"height":84,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=148&h=84&crop=1"},"A3-SMALL-HIDPI":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=296,168","width":296,"height":168,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=296&h=168&crop=1"},"A4":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=268,151","width":268,"height":151,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=268&h=151&crop=1"},"A4-HIDPI":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=536,302","width":536,"height":302,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=536&h=302&crop=1"},"A4-SMALL":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=690,388","width":690,"height":388,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=690&h=388&crop=1"},"XL":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=720,405","width":720,"height":405,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=720&h=405&crop=1"},"social":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=1200,628","width":1200,"height":628,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=1200&h=628&crop=1"},"chapter":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=720,405","width":720,"height":405,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=720"},"200-wide":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=200,113","width":200,"height":113,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=200"},"260-wide":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=260,146","width":260,"height":146,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=260"},"310-wide":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=310,174","width":310,"height":174,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=310"},"420-wide":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=420,236","width":420,"height":236,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=420"},"640-wide":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=640,360","width":640,"height":360,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=640"},"740-wide":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=740,416","width":740,"height":416,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=740"},"75-square":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=75,75","width":75,"height":75,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=75&h=75&crop=1"},"140-square":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=140,140","width":140,"height":140,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=140&h=140&crop=1"},"260-square":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=260,260","width":260,"height":260,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=260&h=260&crop=1"},"160-portrait":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=160,90","width":160,"height":90,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=160"},"320-portrait":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=320,180","width":320,"height":180,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=320"},"200-by-133":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=200,133","width":200,"height":133,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=200&h=133&crop=1"},"740-by-416":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=740,416","width":740,"height":416,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=740&h=416&crop=1"},"540-by-304":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp?resize=540,304","width":540,"height":304,"filesize":104812,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg?w=540&h=304&crop=1"},"full":{"file":"SR_23.05.15_PresidentialRematches_feature.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature.jpg"}},"image_meta":{"aperture":"14","credit":"Getty Images","camera":"Canon EOS R3","caption":"MIAMI, FLORIDA - NOVEMBER 06: Former U.S. President Donald Trump watches a video of President Joe Biden playing during a rally for Sen. Marco Rubio (R-FL) at the Miami-Dade Country Fair and Exposition on November 6, 2022 in Miami, Florida. Rubio faces U.S. Rep. Val Demings (D-FL) in his reelection bid in Tuesday's general election.  (Photo by Joe Raedle\/Getty Images)","created_timestamp":"1667692800","copyright":"2022 Getty Images","focal_length":"124","iso":"320","shutter_speed":"0.0125","title":"Former President Donald Trump Rallies For Marco Rubio In Florida","orientation":"1","keywords":[]},"dominant_color":"493d44","has_transparency":false,"sources":{"image\/webp":{"file":"SR_23.05.15_PresidentialRematches_feature-jpg.webp","filesize":104812}},"original_image":"SR_23.05.15_PresidentialRematches_feature.jpg"},"post":7938,"source_url":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-content\/uploads\/sites\/20\/2023\/05\/SR_23.05.15_PresidentialRematches_feature-jpg.webp","jetpack_videopress_guid":"","jetpack_videopress":{"title":"Former President Donald Trump Rallies For Marco Rubio In Florida","description":"","caption":"","guid":null,"rating":null,"allow_download":0,"display_embed":0,"privacy_setting":2,"needs_playback_token":false,"is_private":false,"private_enabled_for_site":false},"_links":{"self":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media\/9901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/users\/658"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/comments?post=9901"}],"wp:attached-to":[{"embeddable":true,"post_type":"short-read","id":7938,"href":"https:\/\/beta.pewresearch.org\/pewresearch-org\/wp-json\/wp\/v2\/short-read\/7938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}